{"id":10062,"date":"2019-07-27T18:42:09","date_gmt":"2019-07-27T16:42:09","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=10062"},"modified":"2019-07-27T18:33:28","modified_gmt":"2019-07-27T16:33:28","slug":"dj-interview-mit-mario-2","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2","title":{"rendered":"DJ-Interview mit Mario"},"content":{"rendered":"\n<p>Mario alias DJ Sprudler ist seit \u00fcber 20 Jahren leidenschaftlicher DJ. Er tritt vor allem in der <a href=\"https:\/\/www.evely.com\/dj-lahr.html\">Region Nordschwarzwald<\/a> auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. <a href=\"https:\/\/www.evely.com\/djs\/dj-sprudler-2082.html\">Nat\u00fcrlich k\u00f6nnt ihr Mario auch direkt hier buchen.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mario \u00fcber sich selbst &amp; die Musik<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Zur Person<\/h3>\n\n\n\n<p><strong>Wie bist du zu deinem Job gekommen und was fasziniert dich daran? <\/strong><\/p>\n\n\n\n<p>Mit 15 fingen die ersten Partys an, seither stehe ich viel lieber hinterm Mischpult wie davor. Es fasziniert mich immer noch, den Abend musikalisch lenken zu k\u00f6nnen.<\/p>\n\n\n\n<p><strong>Was macht dich als Dienstleister unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n\n\n\n<p>Man sollte mich buchen, weil ich unkompliziert bin, das Rundum-Sorglos-Paket anbiete und aufs Publikum eingehe.<\/p>\n\n\n\n<p><strong>F\u00fcr welche Events eignest du dich besonders gut? <\/strong><\/p>\n\n\n\n<p>Hochzeit, runde Geburtstage, Fasching, Abriss Partys\ud83d\ude1c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Angebot, Technik und Service<\/h3>\n\n\n\n<p><strong>Wie beschreibst du dein Angebot? Z. B. welche Musik oder Lieder spielst du gerne?<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ich stelle mich generell immer auf das Publikum ein.<\/p><\/blockquote>\n\n\n\n<p>Ich stelle mich generell immer auf das Publikum ein. Zum Einen \u00fcber das Vorgespr\u00e4ch, zum Anderen am Abend selbst durch Wunschzettel und Intuition.<\/p>\n\n\n\n<p><strong>Beschreibe deine Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich buchen? Welche Technik, Instrumente etc. bringst du mit?<\/strong><\/p>\n\n\n\n<p>Eine Perfekte Ton und Lichtanlage &#8211; immer dem Anlass entsprechend!<\/p>\n\n\n\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als Dienstleister mit? <\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ich verbreite gute Laune mit meiner Musik.<\/p><\/blockquote>\n\n\n\n<p>Egal, ob 60er oder 18er, Publikum steht im Vordergrund und wird auch so behandelt. Ich verbreite gute Laune mit meiner Musik.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vor der Veranstaltung<\/h3>\n\n\n\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem Dienstleister wie dir f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n\n\n\n<p>Auf langj\u00e4hrige Erfahrung und Bewertungen. Ich werde meistens durch Mundpropaganda weiterempfohlen und das ist die beste Werbung.<\/p>\n\n\n\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n\n\n\n<p>Mit einem gr\u00fcndlichen Vorgespr\u00e4ch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">W\u00e4hrend der Veranstaltung<\/h3>\n\n\n\n<p><strong>Was macht f\u00fcr dich eine gelungene Veranstaltung aus?<\/strong><\/p>\n\n\n\n<p>Gl\u00fcckliche Gesellschaft und gl\u00fccklicher DJ \ud83d\ude04.<\/p>\n\n\n\n<p><strong>Was ist das Schlimmste, das dir ein Gast antun kann? Z. B. f\u00fcnfmal hintereinander \u201eAtemlos\u201c w\u00fcnschen, ins Mischpult greifen, \u2026?<\/strong><\/p>\n\n\n\n<p>Schlechte Laune verbreiten&#8230;<\/p>\n\n\n\n<p><strong>Ist schon mal bei einer deiner Veranstaltungen so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n\n\n\n<p>In der Regel l\u00e4uft alles. Ich habe immer ein Backup dabei, damit nichts schiefgeht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Erfahrung als Dienstleister<\/h3>\n\n\n\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als Dienstleister? <\/strong><\/p>\n\n\n\n<p>Eine Braut war an ihrer Hochzeit so betrunken, dass sie keinen Hochzeitstanz tanzen konnte.<\/p>\n\n\n\n<p><strong>Wie lernt man deinen Job deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man diesen Job machen m\u00f6chte?<\/strong><\/p>\n\n\n\n<p>Jahrelange \u00dcbung.<\/p>\n\n\n\n<p><strong>Was bedeutet <a href=\"https:\/\/www.evely.com\">evely.com<\/a> f\u00fcr dich?<\/strong><\/p>\n\n\n\n<p>EVELY ist eine super Plattform f\u00fcr DJs, die einen auch in Gegenden bringt, in die man sonst nicht kommt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Habt ihr Fragen an Mario?<\/h2>\n\n\n\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview. <a href=\"https:\/\/www.evely.com\/djs\/dj-sprudler-2082.html\">Hier findet ihr weitere Infos zu Mario und k\u00f6nnt ihn direkt f\u00fcr eure Veranstaltung buchen.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mario alias DJ Sprudler ist seit \u00fcber 20 Jahren leidenschaftlicher DJ. Er tritt vor allem in der Region Nordschwarzwald auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Nat\u00fcrlich k\u00f6nnt ihr Mario auch direkt hier buchen. Mario \u00fcber sich selbst &amp; die Musik Zur Person [&hellip;]<\/p>\n","protected":false},"author":587,"featured_media":10065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106,66,68],"tags":[848],"post_status":[],"class_list":["post-10062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","category-kunden","category-interviews","tag-dj-interview"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Mario - EVELY-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Mario - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Mario alias DJ Sprudler ist seit \u00fcber 20 Jahren leidenschaftlicher DJ. Er tritt vor allem in der Region Nordschwarzwald auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Nat\u00fcrlich k\u00f6nnt ihr Mario auch direkt hier buchen. Mario \u00fcber sich selbst &amp; die Musik Zur Person [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-27T16:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kathrin\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Mario - EVELY-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Mario - EVELY-Blog","og_description":"Mario alias DJ Sprudler ist seit \u00fcber 20 Jahren leidenschaftlicher DJ. Er tritt vor allem in der Region Nordschwarzwald auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Nat\u00fcrlich k\u00f6nnt ihr Mario auch direkt hier buchen. Mario \u00fcber sich selbst &amp; die Musik Zur Person [&hellip;]","og_url":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2019-07-27T16:42:09+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png","type":"image\/png"}],"author":"Kathrin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2"},"author":{"name":"Kathrin","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/8dc3db44543d95d52190bdc25babf427"},"headline":"DJ-Interview mit Mario","datePublished":"2019-07-27T16:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png","keywords":["DJ-Interview"],"articleSection":["DJ-Interviews","F\u00fcr Kunden","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2","url":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2","name":"DJ Interview mit Mario - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png","datePublished":"2019-07-27T16:42:09+00:00","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_sprudler-2082-EVELY.jpg.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-mario-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Mario"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/8dc3db44543d95d52190bdc25babf427","name":"Kathrin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","caption":"Kathrin"},"description":"Egal ob Kurz- oder Langstrecke, ob alleine, mit Freunden oder mit der Familie - Kathrin entdeckt in Ihrer Freizeit am liebsten die Welt. Und das am besten immer mit einem guten Buch und Kopfh\u00f6rern in der Tasche. Welche Musik sie damit h\u00f6rt, h\u00e4ngt dann ganz von der Stimmung ab - es darf aber gerne etwas rockiger sein.","url":"https:\/\/www.evely.com\/blog\/author\/kathrin"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/587"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=10062"}],"version-history":[{"count":2,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10062\/revisions"}],"predecessor-version":[{"id":10064,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10062\/revisions\/10064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/10065"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=10062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=10062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=10062"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=10062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}