{"id":10067,"date":"2019-08-01T13:00:56","date_gmt":"2019-08-01T11:00:56","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=10067"},"modified":"2023-09-28T10:08:01","modified_gmt":"2023-09-28T08:08:01","slug":"dj-interview-mit-marcel","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel","title":{"rendered":"DJ-Interview mit Marcel"},"content":{"rendered":"\n<p>Mit langj\u00e4hriger DJ-Erfahrung ist Marcel vor allem in den Regionen <a href=\"https:\/\/www.evely.com\/dj-muenster.html\">M\u00fcnsterland<\/a> und <a href=\"https:\/\/www.evely.com\/alleinunterhalter-nrw.html\">Rheinland<\/a> unterwegs. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Marcel \u00fcber sich selbst &amp; die Musik<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Zur Person<\/h3>\n\n\n\n<p><strong>Wie bist du zu deinem Job gekommen und was fasziniert dich daran? <\/strong><\/p>\n\n\n\n<p>Seitdem ich laufen kann, interessiere ich mich f\u00fcr alles, was mit Musik und Technik zu tun hat. Durch meinen Vater habe ich Musikinstrumente studieren d\u00fcrfen und das Gef\u00fchl f\u00fcr Ton und Rhythmus gelernt. In der Jugend haben mich Boxen und Mischpulte interessiert. So begann ich mit Vaters alten Boxen die ersten Partys zu st\u00fcrmen&#8230;<\/p>\n\n\n\n<p><strong>Was macht dich als Dienstleister unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n\n\n\n<p>Ich habe nicht nur das erforderliche Equipment, sondern kann dies auch entsprechend einsetzten. Die beste Voraussetzung ein guter DJ zu sein, ist es, wenn man schon einmal selber Musik gemacht hat. Ich lege nicht mit Laptop auf, weil das DJing f\u00fcr mich ein Handwerk ist, welches man nicht einem Computer \u00fcberl\u00e4sst.<\/p>\n\n\n\n<p><strong>F\u00fcr welche Events eignest du dich besonders gut? <\/strong><\/p>\n\n\n\n<p>Hochzeiten, Geburtstage, Firmenfeiern&#8230;. \u00dcberall da, wo gefeiert wird \ud83d\ude42<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Angebot, Technik und Service<\/h3>\n\n\n\n<p><strong>Wie beschreibst du dein Angebot? Z. B. welche Musik oder Lieder spielst du gerne?<\/strong><\/p>\n\n\n\n<p>Am liebsten spiele ich die Musik, auf die die G\u00e4ste abfeiern. Da ich in meinem Leben das Gl\u00fcck hatte, mit verschiedensten Musikrichtungen gro\u00df zu werden, bin ich verh\u00e4ltnism\u00e4\u00dfig breit aufgestellt.&nbsp;<\/p>\n\n\n\n<p><strong>Beschreibe deine Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich buchen? Welche Technik, Instrumente etc. bringst du mit?<\/strong><\/p>\n\n\n\n<p>Ich setze auf gute Audio- und Lichttechnik von namhaften Herstellern aus der professionellen Veranstaltungstechnik.<\/p>\n\n\n\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als Dienstleister mit? <\/strong><\/p>\n\n\n\n<p>Gute Laune und ein passendes Gesp\u00fcr f\u00fcr den richtigen Song.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vor der Veranstaltung<\/h3>\n\n\n\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem Dienstleister wie dir f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n\n\n\n<p>Der Kunde braucht auf Nichts besonders achten. Daf\u00fcr bin ich ja da&#8230; .<\/p>\n\n\n\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n\n\n\n<p>Via Telefon oder gerne auch in einem pers\u00f6nlichen Vorgespr\u00e4ch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">W\u00e4hrend der Veranstaltung<\/h3>\n\n\n\n<p><strong>Was macht f\u00fcr dich eine gelungene Veranstaltung aus?<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Der Kunde ist K\u00f6nig<\/p><\/blockquote>\n\n\n\n<p>Das wichtigste ist f\u00fcr mich, dass der Kunde zufrieden ist. Es hei\u00dft ja nicht umsonst &#8220;Der Kunde ist K\u00f6nig.&#8221;<\/p>\n\n\n\n<p><strong>Was ist das Schlimmste, das dir ein Gast antun kann? Z. B. f\u00fcnfmal hintereinander \u201eAtemlos\u201c w\u00fcnschen, ins Mischpult greifen, \u2026?<\/strong><\/p>\n\n\n\n<p>Getr\u00e4nke \u00fcber meine Technik sch\u00fctten&#8230;<\/p>\n\n\n\n<p><strong>Ist schon mal bei einer deiner Veranstaltungen so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n\n\n\n<p>Man kann sich nicht auf einen Patzer vorbereiten. Es war auf einer Hochzeit: Als der Er\u00f6ffnungstanz angek\u00fcndigt wurde, war pl\u00f6tzlich der Strom weg&#8230;. Ich habe das Lied einfach angestimmt und alle haben mitgesungen. \ud83d\ude00<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Erfahrung als Dienstleister<\/h3>\n\n\n\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als Dienstleister? <\/strong><\/p>\n\n\n\n<p>Eine Doppelbuchung&#8230;<\/p>\n\n\n\n<p><strong>Wie lernt man deinen Job deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man diesen Job machen m\u00f6chte?<\/strong><\/p>\n\n\n\n<p>Man sollte viel Know-How im Bereich Musik und Technik mitbringen. Am besten dazu auch noch ein Gef\u00fchl f\u00fcr Menschen und Rhythmus. Wenn man dann noch mit wenig Schlaf und Zeitdruck zurechtkommt, ist man auf einem guten Weg.<\/p>\n\n\n\n<p><strong>Was bedeutet <a href=\"https:\/\/www.evely.com\">evely.com<\/a> f\u00fcr dich?<\/strong><\/p>\n\n\n\n<p>Eine tolle Plattform, um einen perfekt auf den Tag angepassten DJ zu finden &#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Habt ihr Fragen an Marcel?<\/h2>\n\n\n\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit langj\u00e4hriger DJ-Erfahrung ist Marcel vor allem in den Regionen M\u00fcnsterland und Rheinland unterwegs. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Marcel \u00fcber sich selbst &amp; die Musik Zur Person Wie bist du zu deinem Job gekommen und was fasziniert dich daran? Seitdem ich [&hellip;]<\/p>\n","protected":false},"author":587,"featured_media":10070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66,68],"tags":[848],"post_status":[],"class_list":["post-10067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kunden","category-interviews","tag-dj-interview"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Marcel - EVELY-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Marcel - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Mit langj\u00e4hriger DJ-Erfahrung ist Marcel vor allem in den Regionen M\u00fcnsterland und Rheinland unterwegs. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Marcel \u00fcber sich selbst &amp; die Musik Zur Person Wie bist du zu deinem Job gekommen und was fasziniert dich daran? Seitdem ich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-01T11:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T08:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kathrin\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Marcel - EVELY-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Marcel - EVELY-Blog","og_description":"Mit langj\u00e4hriger DJ-Erfahrung ist Marcel vor allem in den Regionen M\u00fcnsterland und Rheinland unterwegs. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Marcel \u00fcber sich selbst &amp; die Musik Zur Person Wie bist du zu deinem Job gekommen und was fasziniert dich daran? Seitdem ich [&hellip;]","og_url":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2019-08-01T11:00:56+00:00","article_modified_time":"2023-09-28T08:08:01+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg","type":"image\/jpeg"}],"author":"Kathrin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel"},"author":{"name":"Kathrin","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/8dc3db44543d95d52190bdc25babf427"},"headline":"DJ-Interview mit Marcel","datePublished":"2019-08-01T11:00:56+00:00","dateModified":"2023-09-28T08:08:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg","keywords":["DJ-Interview"],"articleSection":["F\u00fcr Kunden","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel","url":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel","name":"DJ Interview mit Marcel - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg","datePublished":"2019-08-01T11:00:56+00:00","dateModified":"2023-09-28T08:08:01+00:00","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/07\/dj_marcel-1646-EVELY-2.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/dj-interview-mit-marcel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Marcel"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/8dc3db44543d95d52190bdc25babf427","name":"Kathrin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bda8194b8895ef871b72d28e71f83439bd843be340ad98b87ba6786cfb0169c?s=96&d=mm&r=g","caption":"Kathrin"},"description":"Egal ob Kurz- oder Langstrecke, ob alleine, mit Freunden oder mit der Familie - Kathrin entdeckt in Ihrer Freizeit am liebsten die Welt. Und das am besten immer mit einem guten Buch und Kopfh\u00f6rern in der Tasche. Welche Musik sie damit h\u00f6rt, h\u00e4ngt dann ganz von der Stimmung ab - es darf aber gerne etwas rockiger sein.","url":"https:\/\/www.evely.com\/blog\/author\/kathrin"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/587"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=10067"}],"version-history":[{"count":4,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10067\/revisions"}],"predecessor-version":[{"id":13878,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/10067\/revisions\/13878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/10070"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=10067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=10067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=10067"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=10067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}