{"id":11248,"date":"2020-02-12T12:10:00","date_gmt":"2020-02-12T11:10:00","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=11248"},"modified":"2024-12-02T15:09:54","modified_gmt":"2024-12-02T14:09:54","slug":"hochzeitstrends-2020","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/hochzeitstrends-2020","title":{"rendered":"Hochzeitstrends 2020"},"content":{"rendered":"\n<p>Wir freuen uns, wenn ihr dieses wunderbare Jahr gew\u00e4hlt habt, um euch das Jawort zu geben. Nat\u00fcrlich wollt auch ihr gut vorbereitet in die <a rel=\"noreferrer noopener\" aria-label=\"Planung (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/die-perfekte-hochzeit-planen\" target=\"_blank\">Planung<\/a> eurer Hochzeit starten. Welche Hochzeitstrends ihr euch 2020 nicht entgehen lassen solltet und was es sonst noch f\u00fcr M\u00f6glichkeiten gibt eurer Hochzeitsfeier das besondere Etwas zu verleihen, m\u00f6chten wir euch nun zeigen. Die Hochzeitstrends 2020 werden euch nat\u00fcrliche Farben, Erdt\u00f6ne und einen Hauch <a rel=\"noreferrer noopener\" aria-label=\"Boho Chic (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/romantik-pur-auf-eurer-bohemian-hochzeit-tipps-und-tricks\" target=\"_blank\">Boho Chic<\/a> bescheren. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine Hochzeit im Trend 2020<\/h2>\n\n\n\n<p>Wenn ihr an Hochzeitstrends interessiert seid, dann werden euch die neuen Trends f\u00fcr eure Hochzeit 2020 sehr gefallen. Die Hochzeitstrends 2020 orientieren sich deutlich am Minimalismus Trend, sowie allem, was mit dem Thema Natur in Verbindung gebracht wird. Es wird au\u00dferdem in jeder Hinsicht individueller. Klassisches Hochzeitsdesign wird langsam aber sicher von einem frischen, modernen, nachhaltigen und pers\u00f6nlichem Look abgel\u00f6st. Auch f\u00fcr <a rel=\"noreferrer noopener\" aria-label=\"Weddingplaner (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeitsplaner-werden-in-5-einfachen-schritten-zum-traumjob\" target=\"_blank\">Weddingplaner<\/a> bietet diese neue Richtung eine Vielfalt an M\u00f6glichkeiten, die Kreativit\u00e4t frei laufen zu lassen. Wie das nun genau aussieht, m\u00f6chten wir euch jetzt zeigen. Hier kommt der erste Trend f\u00fcr eure Hochzeit 2020:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hochzeitstrends 2020<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Hochzeitskleider: Der Trend 2020<\/h4>\n\n\n\n<p>Individualisierte Hochzeitskleider waren in den letzten Jahrzehnten eher Mangelware. Die klassische Robe oder Kleider mit gro\u00dfen Reifr\u00f6cken waren das g\u00e4ngige Standardprogramm. Beim <a rel=\"noreferrer noopener\" aria-label=\"Hochzeitskleider (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/vintage-hochzeitskleider-eleganz-und-spitze\" target=\"_blank\">Hochzeitskleider<\/a> Trend 2020 boomt individuelles, futuristisches und elegantes Design. Mit Worten schwer zu beschreiben. Daf\u00fcr gibt es diese tollen Aufnahmen bei Instagram. Wer h\u00e4tte gedacht, dass ein Hosen-Einteiler (siehe zweites Bild) so anmutig und elegant aussehen kann. <\/p>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/B55ARlDisD9\/\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/B5SQvxYHoE3\/\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Trends f\u00fcr eure Hochzeit 2020<\/h2>\n\n\n\n<p>Hier m\u00f6chten wir euch einige Hochzeitstrends f\u00fcr 2020 zeigen, die sich mit Sicherheit auch in Zukunft durchsetzten werden. Dazu z\u00e4hlen individuelle Brautstr\u00e4u\u00dfe, Federn, Holz und andere Naturmaterialien. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Der Brautstrau\u00df<\/strong>: Ein Must-Have auf jeder Hochzeit und dennoch ist er sehr wandelbar. Ein sch\u00f6ner neuer Hochzeitstrend 2020 geht in Richtung Federn und getrockneten Blumen. Es m\u00fcssen n\u00e4mlich nicht immer Rosen sein. Ebenfalls im Kommen sind frische Wildblumen aus dem eigenen Garten, anstatt importierte Massenware.<\/li><li><strong>Nachhaltigkeit<\/strong>: Hochzeiten werden au\u00dferdem zunehmend nachhaltiger. Bio-Buffet, <a rel=\"noreferrer noopener\" aria-label=\"minimalistische Deko (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/minimalistische-hochzeit-der-trend-des-wenigen\" target=\"_blank\">minimalistische Deko<\/a> und <a rel=\"noreferrer noopener\" aria-label=\"Vintage (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/vintage-hochzeitsdeko-10-tipps-fuer-eure-oldschool-feier\" target=\"_blank\">Vintage<\/a> liegen f\u00fcr eure Hochzeit 2020 absolut im Trend .<\/li><li><strong>Atmosph\u00e4re<\/strong>: Eine sch\u00f6ne und entspannte Atmosph\u00e4re ist vielen Brautpaaren sehr wichtig. Das \u00e4u\u00dfert sich deutlich in der Bevorzugung von &#8220;atmosph\u00e4rischer Beleuchtung&#8221;. Nat\u00fcrliche warme T\u00f6ne, ausgefallene Lampenschirme, vielen Kerzen, Lichtw\u00e4nde und anderen romantischen Licht-Installationen sind enorm gefragt. Viele Paare w\u00fcnschen sich au\u00dferdem vermehrte eine <strong>Handy freie Zone<\/strong>, um eine pers\u00f6nliche und gem\u00fctliche Atmosph\u00e4re zu schaffen.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/BgiKVSbj2Uu\/?utm_source=ig_embed\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Trendfarben f\u00fcr eure Hochzeit<\/h2>\n\n\n\n<p>Mit zunehmender Individualit\u00e4t ver\u00e4ndert sich auch die Farbwahl. Pastell T\u00f6ne, Naturfarben und sanfte aufeinander abgestimmte Farbkombinationen sind im Kommen. Auch Kombinationen aus wei\u00dfen und beigen T\u00f6nen liegen sehr im Trend, weil sie perfekt zum eleganten Vintage Look passen. Eines steht damit fest: unaufdringliche und nat\u00fcrliche Hochzeitsdeko ist Trend f\u00fcr 2020. Glitzer und pomp\u00f6s ausgefallene Deko werden zunehmend von der Bildfl\u00e4che verschwinden. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Deko Trends f\u00fcr die Hochzeit<\/h4>\n\n\n\n<p>Besondere <strong><a rel=\"noreferrer noopener\" aria-label=\"Deko Trends (opens in a new tab)\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/minimalistische-hochzeit-der-trend-des-wenigen\" target=\"_blank\">Deko Trends<\/a><\/strong> f\u00fcr die Hochzeit sind zum Beispiel <strong>Blumenkr\u00e4nze aus getrockneten Blumen<\/strong>, ebenso <strong>kleine Ansteckstr\u00e4u\u00dfe<\/strong>. Die klassische Hochzeitstorte wird von sch\u00f6nen mit <a rel=\"noreferrer noopener nofollow\" aria-label=\"essbaren Blumen (opens in a new tab)\" href=\"https:\/\/amzn.to\/2OHW2fE\" target=\"_blank\">essbaren Blumen<\/a> dekorierten <strong>Kuchen <\/strong>abgel\u00f6st. Deko aus <a rel=\"noreferrer noopener nofollow\" aria-label=\"Bast (opens in a new tab)\" href=\"https:\/\/amzn.to\/3brnfgp\" target=\"_blank\">Bast<\/a>, <a rel=\"noreferrer noopener nofollow\" aria-label=\"nat\u00fcrlich gef\u00e4rbten Stoffen (opens in a new tab)\" href=\"https:\/\/amzn.to\/37gnPKH\" target=\"_blank\">nat\u00fcrlich gef\u00e4rbten Stoffen<\/a>, <a rel=\"noreferrer noopener nofollow\" aria-label=\"Boho Chic (opens in a new tab)\"0 href=\"https:\/\/amzn.to\/2OD0lZJ\" target=\"_blank\">Holz<\/a> und <a rel=\"noreferrer noopener nofollow\" aria-label=\"Boho Chic (opens in a new tab)\"1 href=\"https:\/\/amzn.to\/3bt8Wb2\" target=\"_blank\">Federn<\/a> ist 2020 angesagt. <strong>Naturmaterialien<\/strong> m\u00fcssen sparsam und gezielt in Szene gesetzt werden, damit es nicht zu kitschig wird. Ein stillvoll eingesetztes Element, wie dieser traumhafte Foto-Spot, wirkt wahre Wunder.<\/p>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/B71eOrcolL3\/\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Was bleibt?<\/h3>\n\n\n\n<p>Der Hochzeitstrend 2020 liebt traditionelle Elemente ebenso wie neues Design. Ballons,<a rel=\"noreferrer noopener nofollow\" aria-label=\"Boho Chic (opens in a new tab)\"2 href=\"https:\/\/amzn.to\/2HbvEXp\" target=\"_blank\"> Schampus<\/a>, Blumenkinder, <a rel=\"noreferrer noopener nofollow\" aria-label=\"Boho Chic (opens in a new tab)\"3 href=\"https:\/\/www.awin1.com\/awclick.php?gid=341210&amp;mid=11886&amp;awinaffid=519977&amp;linkid=2196599&amp;clickref=\" target=\"_blank\">Blumen-Deko<\/a>, klassische <a rel=\"noreferrer noopener\" aria-label=\"Boho Chic (opens in a new tab)\"4 href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/eine-hochzeit-und-die-sitzordnung-wie-ihr-traditionen-beachtet-und-trotzdem-euren-eigenen-weg-geht\" target=\"_blank\">Sitzordnungen<\/a> &#8211; all das bleibt uns weiterhin erhalten. Der Trend des Individualismus l\u00e4sst einem, wie der Name schon verr\u00e4t, jegliche Freiheit. Somit k\u00f6nnt ihr euch frei f\u00fchlen, die Art von Hochzeit zu feiern, die zu euch passt!<\/p>\n\n\n\n<p>Auf der Suche nach dem passenden <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/vorteile-dj-versus-band\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Boho Chic (opens in a new tab)\"5>DJ oder Musiker<\/a> helfen wir euch gerne weiter. Ihr k\u00f6nnt euch das passende Angebot einfach und bequem <a href=\"https:\/\/www.evely.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Boho Chic (opens in a new tab)\"6>zusammenstellen<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir freuen uns, wenn ihr dieses wunderbare Jahr gew\u00e4hlt habt, um euch das Jawort zu geben. Nat\u00fcrlich wollt auch ihr gut vorbereitet in die Planung eurer Hochzeit starten. Welche Hochzeitstrends ihr euch 2020 nicht entgehen lassen solltet und was es sonst noch f\u00fcr M\u00f6glichkeiten gibt eurer Hochzeitsfeier das besondere Etwas zu verleihen, m\u00f6chten wir euch [&hellip;]<\/p>\n","protected":false},"author":747,"featured_media":11256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66,107],"tags":[1266,1264,1263,1265],"post_status":[],"class_list":["post-11248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kunden","category-hochzeit-planen","tag-heiraten-2020","tag-hochzeit-2020","tag-hochzeitstrends-2020","tag-trend-2020"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hochzeit Trends 2020 - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Hochzeitstrends 2020 begl\u00fccken euch mit minimalistischem Design, aufregend neuen Ideen f\u00fcr Hochzeitskleider und jeder Menge nat\u00fcrlichen Farben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hochzeit Trends 2020 - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Hochzeitstrends 2020 begl\u00fccken euch mit minimalistischem Design, aufregend neuen Ideen f\u00fcr Hochzeitskleider und jeder Menge nat\u00fcrlichen Farben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-12T11:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T14:09:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hochzeit Trends 2020 - EVELY-Blog","description":"Hochzeitstrends 2020 begl\u00fccken euch mit minimalistischem Design, aufregend neuen Ideen f\u00fcr Hochzeitskleider und jeder Menge nat\u00fcrlichen Farben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020","og_locale":"de_DE","og_type":"article","og_title":"Hochzeit Trends 2020 - EVELY-Blog","og_description":"Hochzeitstrends 2020 begl\u00fccken euch mit minimalistischem Design, aufregend neuen Ideen f\u00fcr Hochzeitskleider und jeder Menge nat\u00fcrlichen Farben.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2020-02-12T11:10:00+00:00","article_modified_time":"2024-12-02T14:09:54+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg","type":"image\/jpeg"}],"author":"Maria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020"},"author":{"name":"Maria","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/cf6ae8adeb745eebc37fd9e1d137afc0"},"headline":"Hochzeitstrends 2020","datePublished":"2020-02-12T11:10:00+00:00","dateModified":"2024-12-02T14:09:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020"},"wordCount":688,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg","keywords":["Heiraten 2020","Hochzeit 2020","Hochzeitstrends 2020","Trend 2020"],"articleSection":["F\u00fcr Kunden","Hochzeit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020","url":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020","name":"Hochzeit Trends 2020 - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg","datePublished":"2020-02-12T11:10:00+00:00","dateModified":"2024-12-02T14:09:54+00:00","description":"Hochzeitstrends 2020 begl\u00fccken euch mit minimalistischem Design, aufregend neuen Ideen f\u00fcr Hochzeitskleider und jeder Menge nat\u00fcrlichen Farben.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2020\/02\/desiree-fawn-0tkmbWNLm9E-unsplash.jpg","width":1200,"height":800,"caption":"Hochzeit 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/hochzeitstrends-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Hochzeitstrends 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/cf6ae8adeb745eebc37fd9e1d137afc0","name":"Maria","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","caption":"Maria"},"description":"Ihren bunten Alltag verbringt Maria als Hobby DJane, Yogi, Philosophin und Redakteurin in ihrer Wahlheimat K\u00f6ln. Sie verbringt ihre Freizeit am liebsten an den Str\u00e4nden der k\u00f6lschen Riviera und genie\u00dft nach Feierabend den Blick auf den Rhein. Am liebsten legt Sie alte Disco-Klassiker aus der ganzen Welt auf und noch lieber tanz sie dazu.","url":"https:\/\/www.evely.com\/blog\/author\/maria"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/11248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/747"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=11248"}],"version-history":[{"count":5,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/11248\/revisions"}],"predecessor-version":[{"id":14869,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/11248\/revisions\/14869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/11256"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=11248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=11248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=11248"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=11248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}