{"id":15228,"date":"2025-03-10T09:03:00","date_gmt":"2025-03-10T08:03:00","guid":{"rendered":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten"},"modified":"2025-10-03T22:38:03","modified_gmt":"2025-10-03T20:38:03","slug":"dj-interview-mit-karsten","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten","title":{"rendered":"DJ-Interview mit Karsten"},"content":{"rendered":"<p data-start=\"0\" data-end=\"68\">DJ Karsten Kalender \u2013 30 Jahre Erfahrung hinter den Turntables! Karsten, besser bekannt als DJ Karsten Kalender, bringt beeindruckende <strong data-start=\"145\" data-end=\"167\">30 Jahre Erfahrung<\/strong> als DJ mit und sorgt vor allem in <strong data-start=\"202\" data-end=\"225\">Nordrhein-Westfalen<\/strong> f\u00fcr gro\u00dfartige Stimmung. Damit ihr euch ein besseres Bild von ihm machen k\u00f6nnt, hat er uns einige spannende Interviewfragen beantwortet. Viel Spa\u00df beim Lesen!<\/p>\n<p><a href=\"https:\/\/www.evely.com\/djs\/karsten-6582.html\/lg2g0HcubiEGZZXFTe8Ur4vA5PLBcBKx\" target=\"_blank\" rel=\"noopener noreferrer\">Nat\u00fcrlich k\u00f6nnt ihr Karsten auch direkt hier buchen.<\/a><\/p>\n<h2>Karsten \u00fcber sich selbst<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Warum ist dein Job der beste Job der Welt? Wie bist du dazu gekommen?<\/strong><\/p>\n<p>Schon als Teenager durfte ich auf den ersten Schulfeiern auflegen. In den letzten 30 Jahren habe ich dann \u2013 oft in Kombination mit Livemusik \u2013 zahlreiche private Veranstaltungen musikalisch begleitet und f\u00fcr die richtige Stimmung gesorgt.<\/p>\n<p><strong>Welches Feedback hast du von deinem letzten Kunden bekommen?<\/strong><\/p>\n<p>Folgendes Zitat: &#8220;Ich h\u00e4tte nie gedacht, dass auf meiner Feier so viel getanzt wird \u2013 aber <strong data-start=\"73\" data-end=\"79\">DU<\/strong> hast es m\u00f6glich gemacht!&#8221;<\/p>\n<p><strong>Macht es f\u00fcr dich einen Unterschied, ob du f\u00fcr eine Firmenfeier, eine Hochzeit oder einen Geburtstag gebucht wirst? Welche Events gefallen dir am liebsten?<\/strong><\/p>\n<p>Jede Feier hat ihren ganz eigenen Charme. Wichtig ist, sich gut auf die Veranstaltung vorzubereiten und gleichzeitig flexibel auf spontane Situationen reagieren zu k\u00f6nnen.<\/p>\n<h3>Angebot, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein Angebot? Wie sieht dein Programm aus? <\/strong><\/p>\n<blockquote><p>Ich biete meinen Kunden das <strong data-start=\"28\" data-end=\"58\">rundum sorglose Musikpaket<\/strong>. Egal ob jung oder alt \u2013 die Musik wird individuell auf jede Feier und jeden Geschmack abgestimmt, damit garantiert f\u00fcr jeden etwas dabei ist.<\/p><\/blockquote>\n<p><strong>Beschreibe deine Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich buchen? Welche Technik, Instrumente etc. bringst du mit?<\/strong><\/p>\n<p data-start=\"0\" data-end=\"95\">F\u00fcr jede Veranstaltung stelle ich die passende <strong data-start=\"47\" data-end=\"71\">Ton- und Lichtanlage<\/strong> individuell zusammen. Mindestens <strong data-start=\"108\" data-end=\"126\">zwei Mikrofone<\/strong> sind immer dabei, sodass Reden oder Gesang problemlos m\u00f6glich sind. Dank eines <strong data-start=\"206\" data-end=\"239\">Mischpults mit vielen Kan\u00e4len<\/strong> kann die Anlage sogar als Beschallungssystem f\u00fcr Bands genutzt werden. Als besonderes Highlight biete ich optional ein <strong data-start=\"362\" data-end=\"383\">Live-Saxophon-Set<\/strong> an \u2013 perfekt, um zum Beispiel einer Hochzeitsfeier eine ganz besondere Atmosph\u00e4re zu verleihen.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als Dienstleister mit?<\/strong><\/p>\n<p data-start=\"57\" data-end=\"424\">Auf Wunsch biete ich ein <strong data-start=\"82\" data-end=\"103\">Live-Saxophon-Set<\/strong>, das jeder Veranstaltung eine ganz besondere Note verleiht. Egal ob dezente Hintergrundmusik beim Sektempfang, eine emotionale Untermalung w\u00e4hrend einer Hochzeitszeremonie oder mitrei\u00dfende Saxophon-Solos auf der Tanzfl\u00e4che \u2013 das Saxophon sorgt f\u00fcr eine einzigartige Atmosph\u00e4re und macht das Event noch unvergesslicher. Das Set kann flexibel an den Ablauf der Feier angepasst werden und l\u00e4sst sich perfekt mit meiner DJ-Performance kombinieren, um f\u00fcr eine harmonische Mischung aus Live-Musik und DJ-Sound zu sorgen.<\/p>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Wenn du selbst einen Dienstleister wie dich f\u00fcr deine Hochzeit engagieren w\u00fcrdest, worauf w\u00fcrdest du dann achten?<\/strong><\/p>\n<p>Der <strong data-start=\"4\" data-end=\"27\">pers\u00f6nliche Kontakt<\/strong> ist mir besonders wichtig \u2013 schlie\u00dflich soll die Zusammenarbeit harmonieren und die <strong data-start=\"112\" data-end=\"124\">&#8220;Chemie&#8221;<\/strong> zwischen uns stimmen. Eine gute Verbindung sorgt daf\u00fcr, dass ich genau verstehe, welche Musik und Atmosph\u00e4re ihr euch f\u00fcr eure Veranstaltung w\u00fcnscht.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<p>Vor jeder Buchung biete ich ein <strong data-start=\"32\" data-end=\"60\">kostenloses Erstgespr\u00e4ch<\/strong> an. Dabei lernen wir uns kennen und besprechen gemeinsam, welches Paket am besten zu eurer Veranstaltung passt \u2013 und welche Leistungen vielleicht nicht n\u00f6tig sind. So entsteht ein individuell abgestimmtes Angebot, das perfekt auf eure W\u00fcnsche zugeschnitten ist.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Woran erkennst du, dass dein Auftritt absolut gelungen ist?<\/strong><\/p>\n<blockquote><p>F\u00fcr mich gibt es nichts Sch\u00f6neres, als wenn der Veranstalter und seine G\u00e4ste begeistert sind \u2013 und sich noch lange an die gro\u00dfartige Stimmung und die unvergesslichen Momente der Feier erinnern.<\/p><\/blockquote>\n<p><strong>Was ist das Schlimmste, das dir ein Gast antun kann? Wie gehst du mit schwierigen Situationen um?<\/strong><\/p>\n<p data-start=\"0\" data-end=\"185\">Ich sehe mich als <strong data-start=\"18\" data-end=\"35\">Dienstleister<\/strong>, der es sich zur Aufgabe macht, so viele W\u00fcnsche wie m\u00f6glich zu erf\u00fcllen. Flexibilit\u00e4t und individuelle Anpassung stehen f\u00fcr mich an erster Stelle. Auch in herausfordernden Situationen bleibe ich <strong data-start=\"235\" data-end=\"275\">ruhig, respektvoll und professionell<\/strong>, um stets eine angenehme Atmosph\u00e4re zu bewahren und die bestm\u00f6gliche L\u00f6sung zu finden.<\/p>\n<p><strong>Ist schon mal bei einer deiner Veranstaltungen so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p data-start=\"0\" data-end=\"201\">Beim Aufbau stellte sich heraus, dass eine Bassbox einen technischen Defekt hatte. Dank meines <strong data-start=\"95\" data-end=\"154\">guten Netzwerks zu anderen musikalischen Dienstleistern<\/strong> konnte ich jedoch schnell f\u00fcr Ersatz sorgen. So konnte die Veranstaltung <strong data-start=\"231\" data-end=\"274\">ohne Verz\u00f6gerung und v\u00f6llig reibungslos<\/strong> p\u00fcnktlich starten \u2013 und die G\u00e4ste haben nichts von dem kleinen Zwischenfall mitbekommen.<\/p>\n<h3>Erfahrung als Dienstleister<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als Dienstleister?<\/strong><\/p>\n<p>Folgebuchungen auf mehreren Hochzeiten einer ganzen Freundesgruppe!<\/p>\n<p><strong>Was war bisher dein bester Auftrag oder dein bester Auftragsort (auch international)? Und wo w\u00fcrdest du gerne mal arbeiten?<\/strong><\/p>\n<p data-start=\"0\" data-end=\"181\">Einmal im Jahr habe ich die Ehre, zusammen mit einer <strong data-start=\"53\" data-end=\"99\">gro\u00dfen Band in der Westfalenhalle Dortmund<\/strong> aufzutreten \u2013 ein absolutes Highlight, das mir immer wieder G\u00e4nsehaut bereitet. Ein Traum von mir w\u00e4re es, einmal auf einem <strong data-start=\"227\" data-end=\"247\">Kreuzfahrtschiff<\/strong> aufzulegen und die G\u00e4ste mit meiner Musik mitten auf dem Meer zum Tanzen zu bringen. Vielleicht ergibt sich ja irgendwann die Gelegenheit!<\/p>\n<p><strong>Was w\u00fcrdest du einem Kollegen oder einem Kunden zu EVELY erz\u00e4hlen?<\/strong><\/p>\n<p>Hier findet man genau den passenden Partner f\u00fcr seine Veranstaltung .<\/p>\n<h2>Habt ihr Fragen an Karsten?<\/h2>\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview. <a href=\"https:\/\/www.evely.com\/djs\/karsten-6582.html\/lg2g0HcubiEGZZXFTe8Ur4vA5PLBcBKx\" target=\"_blank\" rel=\"noopener noreferrer\">Hier findet ihr weitere Infos zu Karsten und k\u00f6nnt ihn direkt f\u00fcr eure Veranstaltung buchen.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DJ Karsten Kalender \u2013 30 Jahre Erfahrung hinter den Turntables! Karsten, besser bekannt als DJ Karsten Kalender, bringt beeindruckende 30 Jahre Erfahrung als DJ mit und sorgt vor allem in Nordrhein-Westfalen f\u00fcr gro\u00dfartige Stimmung. Damit ihr euch ein besseres Bild von ihm machen k\u00f6nnt, hat er uns einige spannende Interviewfragen beantwortet. Viel Spa\u00df beim Lesen! [&hellip;]<\/p>\n","protected":false},"author":747,"featured_media":16297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106,68],"tags":[200],"post_status":[],"class_list":["post-15228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","category-interviews","tag-interviews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Karsten - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"DJ Karsten Kalender \u2013 30 Jahre Erfahrung als Event-DJ \ud83c\udfa7 | Exklusives Interview \u00fcber Musik, Leidenschaft &amp; Highlights. Jetzt entdecken! \ud83c\udfb6\ud83d\udd25\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Karsten - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"DJ Karsten Kalender \u2013 30 Jahre Erfahrung als Event-DJ \ud83c\udfa7 | Exklusives Interview \u00fcber Musik, Leidenschaft &amp; Highlights. Jetzt entdecken! \ud83c\udfb6\ud83d\udd25\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T08:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T20:38:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maria\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Karsten - EVELY-Blog","description":"DJ Karsten Kalender \u2013 30 Jahre Erfahrung als Event-DJ \ud83c\udfa7 | Exklusives Interview \u00fcber Musik, Leidenschaft & Highlights. Jetzt entdecken! \ud83c\udfb6\ud83d\udd25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Karsten - EVELY-Blog","og_description":"DJ Karsten Kalender \u2013 30 Jahre Erfahrung als Event-DJ \ud83c\udfa7 | Exklusives Interview \u00fcber Musik, Leidenschaft & Highlights. Jetzt entdecken! \ud83c\udfb6\ud83d\udd25","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2025-03-10T08:03:00+00:00","article_modified_time":"2025-10-03T20:38:03+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png","type":"image\/png"}],"author":"Maria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten"},"author":{"name":"Maria","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/cf6ae8adeb745eebc37fd9e1d137afc0"},"headline":"DJ-Interview mit Karsten","datePublished":"2025-03-10T08:03:00+00:00","dateModified":"2025-10-03T20:38:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten"},"wordCount":910,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png","keywords":["Interviews"],"articleSection":["DJ-Interviews","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten","name":"DJ Interview mit Karsten - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png","datePublished":"2025-03-10T08:03:00+00:00","dateModified":"2025-10-03T20:38:03+00:00","description":"DJ Karsten Kalender \u2013 30 Jahre Erfahrung als Event-DJ \ud83c\udfa7 | Exklusives Interview \u00fcber Musik, Leidenschaft & Highlights. Jetzt entdecken! \ud83c\udfb6\ud83d\udd25","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/03\/karsten-6582.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-interview-mit-karsten#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Karsten"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/cf6ae8adeb745eebc37fd9e1d137afc0","name":"Maria","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f03650fa1028dffd332a56884aae31e9be17347b21dbbc0650df4799bcb584cb?s=96&d=mm&r=g","caption":"Maria"},"description":"Ihren bunten Alltag verbringt Maria als Hobby DJane, Yogi, Philosophin und Redakteurin in ihrer Wahlheimat K\u00f6ln. Sie verbringt ihre Freizeit am liebsten an den Str\u00e4nden der k\u00f6lschen Riviera und genie\u00dft nach Feierabend den Blick auf den Rhein. Am liebsten legt Sie alte Disco-Klassiker aus der ganzen Welt auf und noch lieber tanz sie dazu.","url":"https:\/\/www.evely.com\/blog\/author\/maria"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/15228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/747"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=15228"}],"version-history":[{"count":2,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/15228\/revisions"}],"predecessor-version":[{"id":15235,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/15228\/revisions\/15235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/16297"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=15228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=15228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=15228"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=15228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}