{"id":1916,"date":"2015-12-02T17:00:19","date_gmt":"2015-12-02T15:00:19","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=1916"},"modified":"2023-12-21T15:12:52","modified_gmt":"2023-12-21T14:12:52","slug":"dj-culture-472","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472","title":{"rendered":"DJ-Interview mit Stefan"},"content":{"rendered":"<p>Stefan ist nun schon \u00fcber 16 Jahre im Musikgesch\u00e4ft und bei ihm ist der Kunde K\u00f6nig. Sein Einsatzgebiet erstreckt sich rund um Hessen. Damit du dir ein genaueres Bild von ihm machen kannst, hat er uns im Folgenden einige Interview-Fragen beantwortet.<\/p>\n<h2>Stefan \u00fcber sich selbst, Musik und DJing<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du DJ geworden und was fasziniert dich an dem Job? <\/strong><\/p>\n<p>Im Jahre 1999 hatte ein Gesangsverein hier im Ort sein 140-j\u00e4hriges Jubil\u00e4um und zur Feier gab es eine Discoparty mit DJ-Wettbewerb. Es gab 10 Teilnehmer, 7 Profis und 3 Laien so wie mich. Von diesen 10 Teilnehmern habe ich den 3. Platz belegt und 2 Eintrittskarten f\u00fcr die Musikmesse gewonnen. Dann habe ich das erste Equipment gekauft und die ersten Geburtstage im Freundeskreis begleitet.<\/p>\n<blockquote><p>Mich fasziniert, dass man die Gastgeber an ihren sch\u00f6nsten Tagen begleiten kann.<\/p><\/blockquote>\n<p>Mich fasziniert an diesem Job, dass man immer neue Leute kennenlernt und die Gastgeber an ihren sch\u00f6nsten Tagen begleiten kann. F\u00fcr mich ist es sch\u00f6n, so aus dem Alltag zu entfliehen und einen sch\u00f6nen Abend zu haben. Mich freut es, wenn ich z. B. <a href=\"https:\/\/www.evely.com\/blog\/kunden\/partymusik\/musik-hochzeit\">bei Hochzeiten die Brautpaare begleiten<\/a> kann und so f\u00fcr unvergessliche Stunden sorge. Au\u00dferdem faszinieren mich die Vielfalt der Arten von Veranstaltungen und die unterschiedlichsten Altersgruppen.<\/p>\n<p><strong>Was macht dich als DJ unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<p>Durch meine langj\u00e4hrige Erfahrung von \u00fcber 16 Jahren wei\u00df ich, worauf Deutschland tanzt. Ich habe schon \u00fcber 200 Feiern betreut und dabei alle Arten von Musik aufgelegt. Mein Repertoire umfasst \u00fcber 100.000 einzelne Titel und es kommen laufend viele neue Lieder hinzu. Au\u00dferdem, und das ist mir ein gro\u00dfes Anliegen, sind mir die W\u00fcnsche von Gastgebern und G\u00e4sten sehr wichtig und ich spiele gerne W\u00fcnsche, wenn diese ins Gesamtpaket passen.<\/p>\n<blockquote><p>Durch meine langj\u00e4hrige Erfahrung wei\u00df ich, worauf Deutschland tanzt.<\/p><\/blockquote>\n<p>Des weiteren ist meine Licht- und Tonanlage immer passend zur Location aufgebaut und vor allen Dingen sauber,\u00a0ohne Stolperfallen und st\u00f6rende Kabel. Der Aufbau passiert, bevor die G\u00e4ste eintreffen. Au\u00dferdem, und das best\u00e4tigen mir immer wieder einige Kunden, bin ich immer sehr nett, zuvorkommend, h\u00f6flich, p\u00fcnktlich, immer hilfsbereit und immer gut gelaunt. Au\u00dferdem finde ich es wichtig, dass ein DJ auch durch seinen Kleidungsstil Seriosit\u00e4t ausstrahlt. Ich bin daher immer dem Anlass entsprechend gekleidet.<\/p>\n<p><strong>F\u00fcr welche Events eignest du dich als DJ besonders gut? <\/strong><\/p>\n<p>Es gibt kein Event, was ich nicht durchf\u00fchren w\u00fcrde. Egal ob Hochzeits- und <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/geburtstagsfeier-planen\">Geburtstagsfeiern<\/a>, Club Party, Firmenfeiern, Kirmesveranstaltungen, Fr\u00fchschoppen, Vereinsfeiern und vieles mehr, daf\u00fcr bin ich immer der richtige Ansprechpartner. Durch meine gro\u00dfes Musik-Repertoire ist es mir m\u00f6glich, auf alle Arten von Musik einzugehen. Am liebsten sind mir dennoch die Hochzeitsfeiern, weil es immer spannend ist, ein Brautpaar am sch\u00f6nsten Tag zu begleiten, zumal diese Feiern oft in einem sch\u00f6nen Ambiente stattfinden.<\/p>\n<h3>Musik, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein musikalisches Repertoire? Welche Titel in deiner Musik-Sammlung spielst du besonders gerne?<\/strong><\/p>\n<p>Ich spiele viele Lieder von den 1950er Jahren bis heute. Meine Sammlung besteht aus vielen Discofox-Klassikern und vielen aktuellen Hits aller Genres. Wenn ich gefragt werde, welche Titel ich gerne spiele, antworte ich immer &#8220;alle!&#8221;. Denn wenn ich sagen w\u00fcrde, dass ich am liebsten die Lieder aus einer Richtung spiele, k\u00f6nnte es den Anschein erwecken, dass ich nur solche Musik spiele, aber ich spiele wie erw\u00e4hnt Musik aus allen Richtungen und h\u00f6re auch privat Verschiedenes.<\/p>\n<blockquote><p>Meine Sammlung besteht aus Discofox-Klassikern und aktuellen Hits aller Genres.<\/p><\/blockquote>\n<p>Zum Beispiel gehe ich auf Konzerte von Roland Kaiser, aber auch Konzerte von den \u00c4rzten, Unheilig, Pur, Beatrice Egli, Rammstein und Co habe ich schon besucht. Auf <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/dj-fuer-silvesterfeier\">Silvesterfeiern<\/a> zum Beispiel habe ich in einem Hotel Publikum im Alter von 65+, da spiele ich vorwiegend Schlager der 50er &#8211; 70er Jahre. Dann habe ich wieder eine Vereinsfeier, wo ich die aktuellen Top 100 rauf- und runterspiele. Also verschiedene Veranstaltungen mit verschiedenen Schwerpunkten, was die Musik angeht.<\/p>\n<p><strong>Beschreibe deine technische Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich inklusive DJ-Technik buchen? Arbeitest du mit Schallplatten, CDs oder MP3s? <\/strong><\/p>\n<p>Meine technische Ausstattung besteht aus einem Verst\u00e4rker, 2 Lautsprechern mit Mischpult und Laptop. Das ist die Standard-Variante f\u00fcr bis zu 200 Personen. Dazu kommt noch eine LED-Lichtanlage und eine bunte Disco-Kugel, wenn gew\u00fcnscht. Weiteres Equipment leihe ich mir kosteng\u00fcnstig dazu, wenn der Kunde Sonderw\u00fcnsche hat. Ich lege haupts\u00e4chlich mit\u00a0MP3s auf, aber ab und zu auch mit Schallplatten, doch das eher auf 80er\u00a0Partys.\u00a0Es ist auch kein Problem, von Kunden CDs und Sticks einzulesen, wenn sie besondere Liedw\u00fcnsche haben, z. B. beim\u00a0Er\u00f6ffnungstanz bei Hochzeiten.\u00a0Technik kann ich in allen erdenklichen Gr\u00f6\u00dfen anmieten, Kunden m\u00fcssen mir nur mitteilen, was sie brauchen.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als DJ mit? <\/strong><\/p>\n<blockquote><p>Wo ich auflege, findet die Party oft kein Ende<\/p><\/blockquote>\n<p>Ich lege als DJ nicht nur Musik auf, sondern kann auch &#8211; um die Stimmung anzukurbeln &#8211; mit dem Mikrofon in die Menge gehen und ein paar Hits live zu hochwertig produzierten Playbacks singen, z. B. Thriller, Celebration, Stayi&#8217;n alive, What is love, ein Udo J\u00fcrgens-Medley und aktuelle Hits auf Deutsch und Englisch. \u00dcberall, wo ich bisher aufgelegt habe, war die Tanzfl\u00e4che nahezu immer gut gef\u00fcllt. Durch die W\u00fcnsche der G\u00e4ste fallen mir dazu immer passende Lieder ein, um die Stimmung zu halten. Wo ich auflege, findet die Party oft kein Ende &#8230;<\/p>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem DJ f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<p>Wenn Sie einen DJ buchen wollen, nehmen Sie nicht gleich den g\u00fcnstigsten. Schauen Sie darauf, welche Musikrichtungen der DJ abdecken kann und wie seine Bewertungen und Referenzen aussehen. Sie k\u00f6nnen auch versuchen, \u00fcber andere Kunden etwas \u00fcber den DJ zu erfahren. Es empfiehlt sich, immer ein Vorgespr\u00e4ch mit dem DJ zu f\u00fchren, per Telefon oder pers\u00f6nlich. Ich selbst zum Beispiel habe ein DJ-Blog, wo ich\u00a0\u00fcber die Feiern eine Zusammenfassung schreibe und auch Bilder einstelle. Denn oft vergessen die Kunden, eine Bewertung abzugeben, oder Sie wollen\u00a0keine abgeben. Deshalb erstelle ich meine eigenen Referenzen.\u00a0Wenn der DJ Ihnen ein Angebot macht, vergleichen Sie! Buchen Sie nur das, was Sie auch wirklich brauchen.<\/p>\n<p>Wenn Sie z. B. in einem Club feiern, wo eine Anlage schon da ist, brauchen Sie diese nicht nochmal zu mieten. Aber bedenken Sie eines, und das gebe ich jedem Kunden mit auf den Weg, dem der Preis etwas hoch erscheint: Viele denken nicht daran, dass der DJ weitaus mehr zu leisten hat, als die Musik aufzulegen. Er muss die Technik ein- und ausladen,\u00a0neue Musik anh\u00f6ren, kaufen und einspielen, die Technik pflegen und hier und da Reparaturen durchf\u00fchren.<\/p>\n<blockquote><p>Buchen Sie nur das, was Sie auch wirklich brauchen.<\/p><\/blockquote>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<p>Ich bereite\u00a0mich auf einen Auftritt vor, indem ich w\u00e4hrend des Vorgespr\u00e4ches per\u00a0Telefon, pers\u00f6nlich oder per Internet mit dem Kunden meinen Fragebogen durchgehe. Das\u00a0gibt f\u00fcr mich dann das Grundger\u00fcst f\u00fcr die jeweilige Feier. Wie der Abend abl\u00e4uft, l\u00e4sst sich oft nicht im Vorfeld voraussagen, sodass ich immer \u00f6fters spontan reagieren muss, aber im abgesteckten Rahmen bleibe. Der Kunde kann den Fragebogen auch selbst ausf\u00fcllen und so viele Angaben zur Feier machen. Oft werde ich auch im Vorfeld von G\u00e4sten dieser Feier angerufen, um \u00dcberraschungen zu planen. Das sch\u00f6ne an den Frageb\u00f6gen im Internet ist, dass die Kunden durch die gemachten Angaben direkt sehen k\u00f6nnen, was die Feier kostet, genau so wie hier auf dem Portal von evely.com.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich einen gelungenen Auftritt aus?<\/strong><\/p>\n<p>In einem Satz gesagt: &#8220;Wenn der Gastgeber zufrieden ist!&#8221; Sie kennen Ihre G\u00e4ste besser als der DJ. Wenn Sie wissen, dass Ihre G\u00e4ste Tanzmuffel sind, k\u00f6nnen Sie das dem DJ ruhig im Vorfeld sagen, nicht dass er denkt, er macht alles falsch. Aber eine gelungene Veranstaltung ist f\u00fcr mich immer, wenn viel getanzt wird und die G\u00e4ste sich durch Musikw\u00fcnsche am Abend beteiligen und so zum Gelingen auch etwas beitragen.<\/p>\n<p><strong>Wie reagierst du, wenn z. B. ein Gast betrunken neben dir steht und st\u00e4ndig in dein Mischpult greift oder G\u00e4ste sich denselben Song zum x-ten Mal am Abend w\u00fcnschen?<\/strong><\/p>\n<p>Wenn vorher eine Absprache getroffen wurde, halte ich mich daran. Wenn aber so ein Lied wie &#8220;Atemlos&#8221; mehrmals am Abend l\u00e4uft? Wieso nicht, wenn die G\u00e4ste dazu feiern! Wenn ein Gast sich ungefragt an meinem Pult zu schaffen macht, geht ganz schnell die Musik aus und erst wieder an, wenn der Gast belehrt worden ist, oder nicht mehr mitfeiern darf.<\/p>\n<p><strong>Ist schon mal bei einem deiner Gigs so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Also auf diese Frage brauchte ich bisher keine Antwort. Bisher lief immer alles reibungslos. Au\u00dferdem habe ich in vielen Orten Kollegen sitzen, die mir ggf. beim Versagen der Technik unkompliziert von jetzt auf gleich aushelfen k\u00f6nnen. Nur einmal konnte ich aufgrund eines Autoschadens meinen Auftritt nicht wahrnehmen. Aber ich habe einen kompetenten 1. Wahl-DJ zu der Feier geschickt und alle waren 100 % zufrieden.<\/p>\n<blockquote><p>Bisher lief immer alles reibungslos.<\/p><\/blockquote>\n<h3>Erfahrung als DJ<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als DJ? <\/strong><\/p>\n<p>Bei einer Hochzeit hat der Br\u00e4utigam der Braut einen nagelneuen Mini Cooper in beige geschenkt und die Braut ist vor \u00dcberraschung in meinen Armen umgekippt.<\/p>\n<p><strong>Wie lernt man DJing deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man DJ werden m\u00f6chte?<\/strong><\/p>\n<blockquote><p>Ich habe selbst schon einen Freund zum DJ ausgebildet<\/p><\/blockquote>\n<p>DJ zu werden lernt man am besten in der Praxis. Ich habe mir vieles selbst beigebracht und die jahrelange Erfahrung tut ihr \u00dcbriges. Nur die DJs, die in Clubs auflegen oder beatgenaue \u00dcberg\u00e4nge erstellen wollen, sollten ein paar <a href=\"https:\/\/www.evely.com\/blog\/anbieter\/dj\/tipps\/wie-wird-man-dj-anleitungen\">Workshops<\/a> besuchen. Ich habe selbst schon einen Freund zu einem echten DJ ausgebildet und es hat nur ein halbes Jahr gedauert!<\/p>\n<p><strong>Was bedeutet <a title=\"evely.com\" href=\"https:\/\/www.evely.com\/\">evely.com<\/a> f\u00fcr dich?<\/strong><\/p>\n<p>Als ich vor ca. 3 Jahren per Post die Info \u00fcber evely.com bekommen habe, dachte ich erst, aha, mal sehen was das so bringt. Angemeldet und WOW, nach wenigen Wochen die erste Buchung. Mir gef\u00e4llt, a) dass der Kunde direkt die freien DJs sieht, b) auch den Preis ohne versteckte Kosten und, c) dass wir DJs in den Entwicklungsprozess eingebunden werden und schon hier und da Verbesserungen erreicht haben. Was auch hier heraussticht, ist, dass wir unsere\u00a0ganzen Preisangaben und unsere Verf\u00fcgbarkeit\u00a0etc. im Hintergrund angeben k\u00f6nnen und das Angebot an den Kunden schreiben somit entf\u00e4llt. Ich hoffe, dass 2016 mehr Jobs in Mittelhessen durch EVELY reinkommen. Au\u00dferdem finde ich es okay, daf\u00fcr eine \u00fcbersichtliche Provision zu bezahlen. Ich hoffe, unsere Kundenzahlen wachsen weiter und wir werden das gr\u00f6\u00dfte Team Deutschlands, sodass jeder DJ &#8211; sofern er m\u00f6chte &#8211; jedes Wochenende unterwegs ist.<\/p>\n<p><em>Hast du Fragen an Stefan? Dann hinterlasse einfach einen Kommentar unter diesem Interview.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stefan ist nun schon \u00fcber 16 Jahre im Musikgesch\u00e4ft und bei ihm ist der Kunde K\u00f6nig. Sein Einsatzgebiet erstreckt sich rund um Hessen. Damit du dir ein genaueres Bild von ihm machen kannst, hat er uns im Folgenden einige Interview-Fragen beantwortet. Stefan \u00fcber sich selbst, Musik und DJing Zur Person Wie bist du DJ geworden [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4490,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[167],"post_status":[],"class_list":["post-1916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","tag-dj-culture","quellenhinweis-stefan"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit DJ Culture - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Im Interview mit DJ Culture erf\u00e4hrst du, welche Leistungen er als DJ mitbringt und warum er die Braut auf einer seiner Feiern auffangen musste.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit DJ Culture - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Im Interview mit DJ Culture erf\u00e4hrst du, welche Leistungen er als DJ mitbringt und warum er die Braut auf einer seiner Feiern auffangen musste.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-02T15:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T14:12:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit DJ Culture - EVELY-Blog","description":"Im Interview mit DJ Culture erf\u00e4hrst du, welche Leistungen er als DJ mitbringt und warum er die Braut auf einer seiner Feiern auffangen musste.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit DJ Culture - EVELY-Blog","og_description":"Im Interview mit DJ Culture erf\u00e4hrst du, welche Leistungen er als DJ mitbringt und warum er die Braut auf einer seiner Feiern auffangen musste.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2015-12-02T15:00:19+00:00","article_modified_time":"2023-12-21T14:12:52+00:00","og_image":[{"width":452,"height":594,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg","type":"image\/jpeg"}],"author":"Danny","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472"},"author":{"name":"Danny","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506"},"headline":"DJ-Interview mit Stefan","datePublished":"2015-12-02T15:00:19+00:00","dateModified":"2023-12-21T14:12:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472"},"wordCount":1860,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg","keywords":["DJ Culture"],"articleSection":["DJ-Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472","name":"DJ Interview mit DJ Culture - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg","datePublished":"2015-12-02T15:00:19+00:00","dateModified":"2023-12-21T14:12:52+00:00","description":"Im Interview mit DJ Culture erf\u00e4hrst du, welche Leistungen er als DJ mitbringt und warum er die Braut auf einer seiner Feiern auffangen musste.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/1cab763790df89bdc3be2858b7c988a427430e77.jpeg","width":452,"height":594,"caption":"DJ Culture"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-culture-472#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Stefan"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","caption":"Danny"},"description":"Reisen, Partys, Freunde und Familie sind die wichtigsten Bestandteile in Dannys Leben. Sie ist ein weltoffener Mensch und liebt es, neue Dinge zu entdecken! Neben dem Schreiben von Blog-Artikeln ist sie auch im Service f\u00fcr evely.com t\u00e4tig. Sowohl privat als auch beruflich liebt sie den Kontakt zu Menschen und ist immer neugierig auf andere und neue Meinungen.","url":"https:\/\/www.evely.com\/blog\/author\/danny"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":15,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"predecessor-version":[{"id":14023,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1916\/revisions\/14023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/4490"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=1916"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}