{"id":1927,"date":"2015-12-17T11:45:19","date_gmt":"2015-12-17T09:45:19","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=1927"},"modified":"2019-11-10T16:36:39","modified_gmt":"2019-11-10T15:36:39","slug":"dj-as-257","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-as-257","title":{"rendered":"DJ-Interview mit Andreas"},"content":{"rendered":"<p>Andreas ist Profi, wenn es um Hochzeiten geht! Aber auch bei anderen privaten und \u00f6ffentlichen Veranstaltungen zeigt er, was er in seinen \u00fcber 25 Jahren als DJ bereits gelernt hat. F\u00fcr ihn ist jede Feier individuell und wichtig. Anhand seiner Interview-Antworten kannst du dir ein eigenes Bild \u00fcber Andreas machen. Nat\u00fcrlich kannst du <a href=\"https:\/\/www.evely.com\/djs\/dj-as-257.html\" target=\"_blank\" rel=\"noopener noreferrer\">Andreas auch direkt hier buchen<\/a>. Andreas legt vor allem in <a href=\"https:\/\/www.evely.com\/dj-dueren.html\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00fcren<\/a>, <a href=\"https:\/\/www.evely.com\/dj-koeln.html\" target=\"_blank\" rel=\"noopener noreferrer\">K\u00f6ln<\/a>, <a href=\"https:\/\/www.evely.com\/dj-bonn.html\" target=\"_blank\" rel=\"noopener noreferrer\">Bonn <\/a>und <a href=\"https:\/\/www.evely.com\/dj-duesseldorf.html\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00fcsseldorf <\/a>auf<\/p>\n<h2>Andreas \u00fcber sich selbst, Musik und DJing<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du DJ geworden und was fasziniert dich an dem Job? <\/strong><\/p>\n<p>Ich habe auf einer Veranstaltung damals meine Frau kennengelernt, die selbst eine gro\u00dfe Event-Halle hat. Sie sagte mir, dass ich mein Hobby zum Beruf machen sollte, da sie schon sehr viele DJs kennengelernt h\u00e4tte, die sie aber nicht so \u00fcberzeugt h\u00e4tten wie ich. Ich freue mich besonders und bin darauf stolz, dass ich es jedesmal schaffe, wirklich alle auf die Tanzfl\u00e4che zu bekommen &#8211; darauf gebe ich Garantie!<\/p>\n<p><strong>Was macht dich als DJ unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<blockquote><p>Musikw\u00fcnsche werden bei mir immer umgesetzt<\/p><\/blockquote>\n<p>Ich bin derjenige, der es schafft, jede Veranstaltung in Schwung zu bringen und auf meine Kunden mit Humor und immer guter Laune sowie dem Gesp\u00fcr, im richtigen Moment die passende Musik zu spielen, einzugehen wei\u00df. Musikw\u00fcnsche werden bei mir immer umgesetzt &#8211; spontan oder nach vorheriger Absprache mit dem Kunden.<\/p>\n<p><strong>F\u00fcr welche Events eignest du dich als DJ besonders gut? <\/strong><\/p>\n<div>Ich bin ein Allrounder, der am liebsten auf Hochzeiten und Geburtstagen die Menge zum Toben bringt. Die vielen Firmenevents und Gro\u00dfveranstaltungen, auf denen ich gerade zu den Hauptveranstaltungszeiten wie <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/faschings-karnevals-party-musik-planung\">Karneval<\/a>, Tanz in den Mai, <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/coole-themen-fuer-deine-mottoparty\">Halloween<\/a> oder <a href=\"https:\/\/www.evely.com\/blog\/kunden\/die-besten-ideen-fuer-eure-firmen-weihnachtsfeier\">Weihnachtsfeiern<\/a> spiele, sind jedesmal ein pers\u00f6nliches Highlight, wenn alt und jung zusammen Spa\u00df haben und ausgelassen feiern.<\/div>\n<h3>Musik, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein musikalisches Repertoire? Welche Titel in deiner Musik-Sammlung spielst du besonders gerne?<\/strong><\/p>\n<blockquote><p>Ich spiele alles, was Spa\u00df macht<\/p><\/blockquote>\n<p>Ich habe ein sehr umfangreiches Musikrepertoire, das stets auf dem neuesten Stand ist und f\u00fcr die jeweilige Veranstaltung individuell angepasst wird. Ich spiele alles, was Spa\u00df macht und vom Kunden gew\u00fcnscht wird.<\/p>\n<p><strong>Beschreibe deine technische Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich inklusive DJ-Technik buchen? Arbeitest du mit Schallplatten, CDs oder MP3s? <\/strong><\/p>\n<p>Ich habe meine komplette Lichttechnik auf LEDs umgestellt und gestalte jede Veranstaltung nach vorheriger Absprache individuell zugeschnitten. Gerne kommen hier auch Laser zum Einsatz. Musik spiele ich \u00fcber CDs und\/oder Mp3s ab. Bands und andere Akteure k\u00f6nnen sich gerne bei mir mit &#8220;einst\u00f6pseln&#8221;. Funkmikros und Headset habe ich immer dabei und sie kosten nat\u00fcrlich nichts extra. Die beste Musik passt nicht ohne passenden Sound &#8211; daher spiele ich auf Fohhn.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als DJ mit? <\/strong><\/p>\n<div>Meine St\u00e4rke liegt darin, im richtigen Moment die passende Musik zu spielen und ein Gesp\u00fcr daf\u00fcr zu haben, wenn gew\u00fcnscht die passende Moderation gezielt einzusetzen. Diese unterst\u00fctze ich mit professioneller Technik.<\/div>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem DJ f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<blockquote><p>Erfahrung und Einf\u00fchlungsverm\u00f6gen des DJs spielen eine gro\u00dfe Rolle.<\/p><\/blockquote>\n<p>Am Besten ist immer eine Empfehlung aus dem Bekanntenkreis oder von jemandem, der den DJ pers\u00f6nlich kennt. Erfahrung und Einf\u00fchlungsverm\u00f6gen des DJs spielen eine gro\u00dfe Rolle. Beim ersten Gespr\u00e4ch h\u00f6rt man schnell raus, ob die Chemie passt und die n\u00f6tigen Vorraussetzungen stimmen und umgesetzt werden k\u00f6nnen.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<p>Jede Veranstaltung wird mit dem Kunden vorher durchgesprochen und genau abgestimmt. Angefangen bei der gew\u00fcnschten Ton- und Lichttechnik \u00fcber die Musikauswahl bis hin zu den verschiedenen Tages-\/Abendabschnitten. Ich baue die Technik immer so auf, dass wenn der erste Gast eintrifft, alles fertig ist und ein Licht- und Soundcheck gemacht worden ist.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich einen gelungenen Auftritt aus?<\/strong><\/p>\n<p>Die Zufriedenheit aller G\u00e4ste ist mir sehr wichtig. Deshalb binde ich auf jeder Veranstaltung alle Anwesenden in das Event mit ein.<\/p>\n<p><strong>Wie reagierst du, wenn z. B. ein Gast betrunken neben dir steht und st\u00e4ndig in dein Mischpult greift oder G\u00e4ste sich denselben Song zum x-ten Mal am Abend w\u00fcnschen?<\/strong><\/p>\n<p>Gelassen, mit Humor sage ich ihm, dass das gew\u00fcnschte Lied schon des \u00f6fteren gespielt worden ist. Mir hat bisher noch nie jemand ungewollt ins Mischpult gegriffen. Ich beziehe aber regelm\u00e4\u00dfig gerne die J\u00fcngsten mit ein und lasse sie mir bei der Arbeit &#8220;helfen&#8221;.<\/p>\n<p><strong>Ist schon mal bei einem deiner Gigs so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Toi toi toi, bisher lief alles immer glatt. Da ich vorher alles genau plane und durchchecke, bin ich vor \u00dcberraschungen sicher.<\/p>\n<h3>Erfahrung als DJ<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als DJ? <\/strong><\/p>\n<blockquote><p>Eine Metal&amp;Rock-Hochzeit, die fast zwei Tage am St\u00fcck durchgefeiert wurde<\/p><\/blockquote>\n<p>Zuerst nat\u00fcrlich das Kennenlernen meiner Frau auf einer gro\u00dfen Karnevalsveranstaltung, wo ich zusammen mit Col\u00f6r, Fussich Julchen und den R\u00e4ubern meinen Heiratsantrag inzenierte. Dann eine Metal&amp;Rock-Hochzeit, die fast zwei Tage am St\u00fcck durchgefeiert wurde. Ich hatte aber unter den vielen internationalen Hochzeiten, die ich gemacht habe (\u00fcber 600), eine \u00e4thiopische Hochzeitszeremonie, die mit einer riesigen Trommlergruppe das Schloss &#8220;st\u00fcrmte&#8221; und fast die Fenstergl\u00e4ser zum Platzen brachte &#8211; diese auf &#8220;kundenfreundliche&#8221; Lautst\u00e4rke zum Spielen zu bewegen, war sehr lustig, weil sie dachten, ich wolle mit trommeln.<\/p>\n<p>Mir kommen aber regelm\u00e4\u00dfig die Tr\u00e4nen, wenn nach einer Veranstaltung der Kunde mit strahlenden Augen zu mir kommt und sagt, wie zufrieden und gl\u00fccklich er ist und ich auf der n\u00e4chsten Feier auf jeden Fall wieder dabei bin.<\/p>\n<p><strong>Wie lernt man DJing deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man DJ werden m\u00f6chte?<\/strong><\/p>\n<p>Zuerst einmal \u00fcben, \u00fcben, \u00fcben. Ganz wichtig neben der passenden Musik ist es, dem Kunden zu zeigen, das er sich zu 100% auf mich verlassen kann und in guten H\u00e4nden ist. Erfahrung kann man nicht kaufen, sondern muss sie selbst erleben.<\/p>\n<p><strong>Was bedeutet <a title=\"evely.com\" href=\"https:\/\/www.evely.com\/\">evely.com<\/a> f\u00fcr dich?<\/strong><\/p>\n<p>evely.com halte ich f\u00fcr ein \u00fcberaus professionelles Portal, um gute K\u00fcnstler f\u00fcr jede Anforderung buchen zu k\u00f6nnen.<\/p>\n<p><em>Hast du Fragen an Andreas? Dann hinterlasse einfach einen Kommentar unter diesem Interview. <a href=\"https:\/\/www.evely.com\/djs\/dj-as-257.html\" target=\"_blank\" rel=\"noopener noreferrer\">Hier findest du noch mehr Infos zu Andreas und kannst ihn direkt f\u00fcr deine Veranstaltung buchen<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andreas ist Profi, wenn es um Hochzeiten geht! Aber auch bei anderen privaten und \u00f6ffentlichen Veranstaltungen zeigt er, was er in seinen \u00fcber 25 Jahren als DJ bereits gelernt hat. F\u00fcr ihn ist jede Feier individuell und wichtig. Anhand seiner Interview-Antworten kannst du dir ein eigenes Bild \u00fcber Andreas machen. Nat\u00fcrlich kannst du Andreas auch [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106,68],"tags":[169],"post_status":[],"class_list":["post-1927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","category-interviews","tag-dj-as","quellenhinweis-andreas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Andreas (DJ AS) - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Mit seinem umfangreichen Musikrepertoire und seiner Erfahrung geht DJ AS auf jeden Kunden individuell ein. Lies das gesamte Interview mit DJ AS hier bei uns\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Andreas (DJ AS) - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Mit seinem umfangreichen Musikrepertoire und seiner Erfahrung geht DJ AS auf jeden Kunden individuell ein. Lies das gesamte Interview mit DJ AS hier bei uns\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-17T09:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-10T15:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Andreas (DJ AS) - EVELY-Blog","description":"Mit seinem umfangreichen Musikrepertoire und seiner Erfahrung geht DJ AS auf jeden Kunden individuell ein. Lies das gesamte Interview mit DJ AS hier bei uns","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Andreas (DJ AS) - EVELY-Blog","og_description":"Mit seinem umfangreichen Musikrepertoire und seiner Erfahrung geht DJ AS auf jeden Kunden individuell ein. Lies das gesamte Interview mit DJ AS hier bei uns","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2015-12-17T09:45:19+00:00","article_modified_time":"2019-11-10T15:36:39+00:00","og_image":[{"width":667,"height":1000,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg","type":"image\/jpeg"}],"author":"Danny","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257"},"author":{"name":"Danny","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506"},"headline":"DJ-Interview mit Andreas","datePublished":"2015-12-17T09:45:19+00:00","dateModified":"2019-11-10T15:36:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257"},"wordCount":1101,"commentCount":1,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg","keywords":["DJ AS"],"articleSection":["DJ-Interviews","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257","name":"DJ Interview mit Andreas (DJ AS) - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg","datePublished":"2015-12-17T09:45:19+00:00","dateModified":"2019-11-10T15:36:39+00:00","description":"Mit seinem umfangreichen Musikrepertoire und seiner Erfahrung geht DJ AS auf jeden Kunden individuell ein. Lies das gesamte Interview mit DJ AS hier bei uns","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/11\/Dj-As-Portrait-e1450363814978.jpg","width":667,"height":1000,"caption":"Interview mit DJ AS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/dj-as-257#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Andreas"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","caption":"Danny"},"description":"Reisen, Partys, Freunde und Familie sind die wichtigsten Bestandteile in Dannys Leben. Sie ist ein weltoffener Mensch und liebt es, neue Dinge zu entdecken! Neben dem Schreiben von Blog-Artikeln ist sie auch im Service f\u00fcr evely.com t\u00e4tig. Sowohl privat als auch beruflich liebt sie den Kontakt zu Menschen und ist immer neugierig auf andere und neue Meinungen.","url":"https:\/\/www.evely.com\/blog\/author\/danny"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=1927"}],"version-history":[{"count":8,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1927\/revisions"}],"predecessor-version":[{"id":10846,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/1927\/revisions\/10846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/1949"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=1927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=1927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=1927"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=1927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}