{"id":2081,"date":"2018-12-18T11:00:21","date_gmt":"2018-12-18T10:00:21","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=2081"},"modified":"2024-12-30T12:13:10","modified_gmt":"2024-12-30T11:13:10","slug":"weihnachten-ausgehtipps","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps","title":{"rendered":"Party an Weihnachten 2018: Ausgehtipps f\u00fcr 5 deutsche Gro\u00dfst\u00e4dte"},"content":{"rendered":"<p>Genug vom besinnlichen Weihnachten im Kreise der Liebsten? Genug vom vielen Essen und von <a href=\"https:\/\/www.evely.com\/blog\/kunden\/partymusik\/weihnachtsmusik\">Weihnachtsmusik<\/a> \u00e0 la &#8220;O du fr\u00f6hliche&#8221;? Dann wird es Zeit, sich ins Partyoutfit zu schmei\u00dfen und Freunde zusammenzutrommeln. Denn Weihnachten ist nicht nur das Fest der Liebe, sondern auch eine sehr gute Gelegenheit zum Feiern.<\/p>\n<p>Ihr fragt euch, wo an Weihnachten 2018 die besten Partys in ganz Deutschland steigen? Wir haben die Antworten f\u00fcr euch!<\/p>\n<h2>Ausgehen an Weihnachten 2018: feiern und tanzen<\/h2>\n<p>F\u00fcr euch haben wir uns auf die Suche gemacht, wo ihr in Berlin, Hamburg, K\u00f6ln, Frankfurt und M\u00fcnchen dieses Jahr an Weihnachten weggehen, mit Freunden feiern und abtanzen k\u00f6nnt. Hier also nun ein kleiner, aber feiner Teil der Ausgeh-M\u00f6glichkeiten an Weihnachten in den jeweiligen St\u00e4dten.<\/p>\n<p>Wir w\u00fcnschen euch ein weltklasse extra langes Weihnachtswochenende!<\/p>\n<h2>Weihnachtspartys in M\u00fcnchen<\/h2>\n<h3>Pimpernel<\/h3>\n<p>Das Pimpernel steht f\u00fcr einen bunten Mix aus G\u00e4sten aller Altersstufen, Sexualit\u00e4ten und, und, und. Es fungierte bereits als &#8220;Etablissement&#8221;, Gay-Bar und vieles mehr. Klar, dass in dem legend\u00e4ren Club auch an Weihnachten die Luzie abgeht. Hier wird generell bis in die fr\u00fchen Morgenstunden hineingetanzt. Wenn ihr auf Electro steht, ist das eure Adresse!<\/p>\n<ul>\n<li>Wann: 24.12.2018, ab 22.00 Uhr<\/li>\n<li>Wo:\u00a0M\u00fcllerstr. 56, 80469 M\u00fcnchen<\/li>\n<li>Musik: Techno, Elektro<\/li>\n<li>Eintritt: 10 \u20ac<\/li>\n<li>Web: <a href=\"http:\/\/www.pimpernel.de\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">http:\/\/www.pimpernel.de<\/a><\/li>\n<\/ul>\n<h3>Ampere im Muffatwerk<\/h3>\n<p>Am ersten Weihnachtstag geht&#8217;s f\u00fcr feinste elektronische Beats ins Ampere. Der Veranstaltungsraum im Muffatwerk bietet eine interessante Kombination aus altem Dachwerk mit modernen industriellen Elementen. Sein Charme ist ber\u00fchmt ber\u00fcchtigt, also hin da!<\/p>\n<ul>\n<li>Wann: 25.12.2018, ab 20.00 Uhr<\/li>\n<li>Wo: Zellstr. 4, 81667 M\u00fcnchen<\/li>\n<li>Musik: Electro, Techno<\/li>\n<li>Eintritt: keine Angabe<\/li>\n<li>Web: <a href=\"https:\/\/www.muffatwerk.de\/de\/events\/view\/4239\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.muffatwerk.de<\/a><\/li>\n<\/ul>\n<h2>Hier feiert Frankfurt Weihnachten<\/h2>\n<h3>AdLib<\/h3>\n<p>Das AdLib in Frankfurt ist eine h\u00f6chst edle Location, die sich perfekt f\u00fcr das weihnachtliche Clubbing anbietet. Hoch \u00fcber den D\u00e4chern der Stadt l\u00e4sst es sich hier wunderbar an den Feiertagen abtanzen. Auf drei Etagen werdet ihr mit allem versorgt, was euer Herz begehrt.<\/p>\n<ul>\n<li>Wann: 25.12.2018, ab 22.00 Uhr<\/li>\n<li>Wo: Schwedler Strasse 8, 60314 Frankfurt<\/li>\n<li>Musik: gemischt<\/li>\n<li>Eintritt: 10 \u20ac (8 \u20ac bis 24 Uhr)<\/li>\n<li>Web: <a href=\"http:\/\/www.adlib-ffm.de\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">http:\/\/www.adlib-ffm.de<\/a><\/li>\n<\/ul>\n<h2>Weihnachtliches Clubbing in Berlin<\/h2>\n<h3>Ritter Butzke<\/h3>\n<p>An Heiligabend wird es housig im Berliner Ritter Butzke: House pur zum Abtanzen nach der Bescherung. &#8220;KnusperHouse&#8221; hei\u00dft die hauseigene Weihnachtsparty des Ritters.<\/p>\n<ul>\n<li>Wann: 24.12.2015, ab 24.00 Uhr<\/li>\n<li>Wo: Ritterstr. 26, 10969 Berlin<\/li>\n<li>Musik: House<\/li>\n<li>Eintritt: 11 &#8211; 13 Euro<\/li>\n<li>Web: <a href=\"https:\/\/club.ritterbutzke.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/club.ritterbutzke.com<\/a><\/li>\n<\/ul>\n<h3>:\/\/about blank<\/h3>\n<p>Im &#8220;blank&#8221; gibt es am ersten Weihnachtstag elektronische T\u00f6ne auf die Oren. Wer nach den Festivit\u00e4ten ein umfassendes Cardio-Training ben\u00f6tigt, ist hier goldrichtig.<\/p>\n<ul>\n<li>Wann: 25.12.2018, ab 24.00 Uhr<\/li>\n<li>Wo: Markgrafendamm 24c, 10245 Berlin<\/li>\n<li>Musik: Electro<\/li>\n<li>Eintritt: 13,50 Euro<\/li>\n<li>Web: <a href=\"http:\/\/aboutblank.li\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">http:\/\/aboutblank.li<\/a><\/li>\n<\/ul>\n<h2>Wo tanzt K\u00f6ln an Weihnachten?<\/h2>\n<h3>Gew\u00f6lbe<\/h3>\n<p>Heiligabend im Gew\u00f6lbe: Der Titel der Party verr\u00e4t noch nichts vom schillernden Glanz der Gew\u00f6lbe-Partys! Mit dabei ist sogar eine g\u00e4nzlich neu interpretierte Weihnachtsgeschichte, die ihr auf Facebook bewundern k\u00f6nnt.<\/p>\n<ul>\n<li>Wann: 24.12.2018, ab 24 Uhr<\/li>\n<li>Wo: Hans-B\u00f6ckler-Platz 2, 50672 K\u00f6ln<\/li>\n<li>Musik: Elektro<\/li>\n<li>Eintritt: keine Angabe<\/li>\n<li>Web: <a href=\"http:\/\/www.gewoelbe.net\" rel=\"nofollow\" target=\"_blank\">http:\/\/www.gewoelbe.net<\/a><\/li>\n<\/ul>\n<h3>Stadtgarten, Studio 672<\/h3>\n<p>\u00c0 la &#8220;Christmas Groove&#8221; wird im Studio 672 in K\u00f6ln gefeiert. Das Besondere an dieser Party ist, dass hier DJ-Duos gewichtelt werden und anschlie\u00dfend gemeinsam f\u00fcr eine bebende Tanzfl\u00e4che sorgen sollen. Es bleibt spannend!<\/p>\n<ul>\n<li>Wann: 25.12.2018, ab 23.00 Uhr<\/li>\n<li>Wo: Venloer Stra\u00dfe 40, 50672 K\u00f6ln<\/li>\n<li>Musik: House, Soul, Funk &amp; Techno<\/li>\n<li>Eintritt: 8 \u20ac<\/li>\n<li>Web:<a href=\"https:\/\/www.stadtgarten.de\/\" target=\"_blank\" rel=\"nofollow\"> http:\/\/www.stadtgarten.de\/<\/a><\/li>\n<\/ul>\n<h2>HoHoHo in Hamburg<\/h2>\n<h3>Fundbureau<\/h3>\n<p>An Weihnachten l\u00e4dt die Streunerkatze zum Tanz im Fundbureu ein. Fast schon famili\u00e4r geht es hier zu, w\u00e4hrend zu elektronischer Musik aller Sorten getanzt wird.<\/p>\n<ul>\n<li>Wann: 25.12.2018, ab 24 Uhr<\/li>\n<li>Wo: Stresemannstra\u00dfe 114, 22769 Hamburg<\/li>\n<li>Musik: Elektronische Musik<\/li>\n<li>Eintritt: 10 \u20ac<\/li>\n<li>Web: <a href=\"https:\/\/www.instagram.com\/fundbureau_hh\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/fundbureau.de<\/a><\/li>\n<\/ul>\n<h3>Eberts<\/h3>\n<p>Hamburgs KULT-Disco setzt an Weihnachten nicht auf Weihnachtsbraten und Tannenbaum, sondern auf aktuelle Charts und die ein oder andere Weihnachtsscheibe. Hier k\u00f6nnt ihr an Heiligabend getrost bis in die fr\u00fchen Morgenstunden feiern.<\/p>\n<ul>\n<li>Wann: 24.12.2018, ab 22.00 Uhr<\/li>\n<li>Wo: Friedrich-Ebert-Allee 3-11, 22869 Schenefeld<\/li>\n<li>Musik: aktuelle Charts<\/li>\n<li>Eintritt: 10 \u20ac<\/li>\n<li>Web: <a href=\"https:\/\/eberts.de\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">http:\/\/eberts.de<\/a><\/li>\n<\/ul>\n<p><strong>\u00dcbrigens:<\/strong> Viele Club- und Konzerttickets k\u00f6nnt ihr auch <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=338581&amp;mid=11388&amp;awinaffid=519977&amp;linkid=2174354&amp;clickref=\" target=\"_blank\" rel=\"\u201dnofollow\u201d noopener noreferrer\" rel=\"nofollow\">bei Eventim kaufen.<\/a> Sucht euch direkt euren Favoriten aus!<\/p>\n<h2>Schmei\u00dft ihr lieber eure eigene Weihnachtsparty?<\/h2>\n<p>Bei evely.com findet ihr den richtigen <a href=\"https:\/\/www.evely.com\/dj-weihnachtsfeier.html\" target=\"_blank\" rel=\"noopener noreferrer\">DJ f\u00fcr die Weihnachtsfeier<\/a>.<\/p>\n<p>Au\u00dferdem freuen wir uns \u00fcber Tipps und Kommentare zu weiteren Partylocations f\u00fcr Xmas und w\u00fcnschen euch allen ein frohes, partyreiches und weltklasse Weihnachten 2018!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Genug vom besinnlichen Weihnachten im Kreise der Liebsten? Genug vom vielen Essen und von Weihnachtsmusik \u00e0 la &#8220;O du fr\u00f6hliche&#8221;? Dann wird es Zeit, sich ins Partyoutfit zu schmei\u00dfen und Freunde zusammenzutrommeln. Denn Weihnachten ist nicht nur das Fest der Liebe, sondern auch eine sehr gute Gelegenheit zum Feiern. Ihr fragt euch, wo an Weihnachten [&hellip;]<\/p>\n","protected":false},"author":483,"featured_media":2140,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[108],"tags":[12,177],"post_status":[],"class_list":["post-2081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines","tag-party","tag-weihnachten","quellenhinweis-vladans-dollar-photo-club"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausgeht Tipps f\u00fcr Weihnachten 2018 \u2013 f\u00fcnf Gro\u00dfst\u00e4dte - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Hier findet ihr die 10 besten Partys an Weihnachten in Berlin, M\u00fcnchen, Frankfurt, Hamburg und K\u00f6ln. Viel Spa\u00df beim Xmas-Clubbing &amp; besinnlichen Feiern!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausgeht Tipps f\u00fcr Weihnachten 2018 \u2013 f\u00fcnf Gro\u00dfst\u00e4dte - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Hier findet ihr die 10 besten Partys an Weihnachten in Berlin, M\u00fcnchen, Frankfurt, Hamburg und K\u00f6ln. Viel Spa\u00df beim Xmas-Clubbing &amp; besinnlichen Feiern!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T10:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T11:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Levi\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausgeht Tipps f\u00fcr Weihnachten 2018 \u2013 f\u00fcnf Gro\u00dfst\u00e4dte - EVELY-Blog","description":"Hier findet ihr die 10 besten Partys an Weihnachten in Berlin, M\u00fcnchen, Frankfurt, Hamburg und K\u00f6ln. Viel Spa\u00df beim Xmas-Clubbing & besinnlichen Feiern!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps","og_locale":"de_DE","og_type":"article","og_title":"Ausgeht Tipps f\u00fcr Weihnachten 2018 \u2013 f\u00fcnf Gro\u00dfst\u00e4dte - EVELY-Blog","og_description":"Hier findet ihr die 10 besten Partys an Weihnachten in Berlin, M\u00fcnchen, Frankfurt, Hamburg und K\u00f6ln. Viel Spa\u00df beim Xmas-Clubbing & besinnlichen Feiern!","og_url":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2018-12-18T10:00:21+00:00","article_modified_time":"2024-12-30T11:13:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg","type":"image\/jpeg"}],"author":"Levi","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps"},"author":{"name":"Levi","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/5c9e3fbcf1377b605d153349976875a5"},"headline":"Party an Weihnachten 2018: Ausgehtipps f\u00fcr 5 deutsche Gro\u00dfst\u00e4dte","datePublished":"2018-12-18T10:00:21+00:00","dateModified":"2024-12-30T11:13:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps"},"wordCount":724,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg","keywords":["Party","Weihnachten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps","url":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps","name":"Ausgeht Tipps f\u00fcr Weihnachten 2018 \u2013 f\u00fcnf Gro\u00dfst\u00e4dte - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg","datePublished":"2018-12-18T10:00:21+00:00","dateModified":"2024-12-30T11:13:10+00:00","description":"Hier findet ihr die 10 besten Partys an Weihnachten in Berlin, M\u00fcnchen, Frankfurt, Hamburg und K\u00f6ln. Viel Spa\u00df beim Xmas-Clubbing & besinnlichen Feiern!","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2015\/12\/Dollarphotoclub_95464143.jpg","width":1200,"height":800,"caption":"Party an Weihnachten"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/allgemeines\/weihnachten-ausgehtipps#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Party an Weihnachten 2018: Ausgehtipps f\u00fcr 5 deutsche Gro\u00dfst\u00e4dte"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/5c9e3fbcf1377b605d153349976875a5","name":"Levi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/efbb0ae2b015dd4457ba0ba491b7f03216b1a73c9cad7272bceeed720dc12ca6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efbb0ae2b015dd4457ba0ba491b7f03216b1a73c9cad7272bceeed720dc12ca6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efbb0ae2b015dd4457ba0ba491b7f03216b1a73c9cad7272bceeed720dc12ca6?s=96&d=mm&r=g","caption":"Levi"},"description":"Levi wei\u00df nicht, ob sein Herz mehr f\u00fcr Musik oder das Schreiben schl\u00e4gt. Deshalb kombiniert er am liebsten beides und mixt Themen und Genres wild durcheinander. Seine Lieblingsmusik reicht von Klassik bis Deutschrap, Schlager m\u00fcssen allerdings drau\u00dfen bleiben. Sein Lieblingsinstrument ist das Saxophon. Nur Noten lesen kann er noch nicht.","url":"https:\/\/www.evely.com\/blog\/author\/paola"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/483"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=2081"}],"version-history":[{"count":50,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2081\/revisions"}],"predecessor-version":[{"id":15135,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2081\/revisions\/15135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/2140"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=2081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=2081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=2081"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=2081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}