{"id":2398,"date":"2016-03-16T12:01:32","date_gmt":"2016-03-16T11:01:32","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=2398"},"modified":"2024-12-29T18:16:07","modified_gmt":"2024-12-29T17:16:07","slug":"dj-udo-284","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284","title":{"rendered":"DJ-Interview mit Udo"},"content":{"rendered":"<p>Mit seiner langj\u00e4hrigen Erfahrung verspricht Udo seinen Kunden und G\u00e4sten ein umfangreiches Musikrepertoire: <span class=\"textTab\"> &#8220;Mein Musikarchiv wird st\u00e4ndig aktualisiert, zu Veranstaltungen komme ich mit rund 160.000 Titeln. Da wird es nie langweilig!&#8221;. Seine Lichttechnik stammt aus dem Profibereich und genauso wichtig ist f\u00fcr Udo eine gute Vorbereitung. Mit dem folgenden Interview k\u00f6nnt ihr euch einen guten Eindruck von Udo machen.<\/span><\/p>\n<h2>Udo \u00fcber sich selbst, Musik und DJing<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du DJ geworden und was fasziniert dich an dem Job?<\/strong><\/p>\n<blockquote><p>Musik zu spielen und Leute zum Tanzen zu bewegen<\/p><\/blockquote>\n<p>Seid meinem 13. Lebensjahr h\u00f6re ich gerne Musik. Gepr\u00e4gt wurde das durch meine Geschwister (die \u00e4lter sind als ich).Wir hatten Zuhause einen Partykeller mit Licht und einer Musikanlage. Dort wurden Partys veranstaltet und oftmals durfte ich zu Anfang Musik auflegen. Das hat mich gepr\u00e4gt. Ich kaufte Kassetten und Singles von meinem Taschengeld. Einige Jahre sp\u00e4ter hatte ich die Gelegenheit, in einem Jugendzentrum erstmalig vor fremden Menschen Musik aufzulegen. Ab da war mir klar, das ist etwas, was mir liegt: Musik zu spielen und Leute zum Tanzen zu bewegen. Die n\u00e4chste Station war dann eine Disco, in der ich die Chance bekam, als DJ aufzulegen. Alles noch mit Schallplatten. Nach der Disco begann dann der Weg als Mobiler DJ.<\/p>\n<p><strong>Was macht dich als DJ unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<p>Meine Erfahrung und positive Energie. Der Kunde schenkt mir sein Vertrauen, eine gelungene Party mit Musik zu gestalten. Und das setzte ich mit guter Vorbereitung, viel Erfahrung und Technik aus dem Profibereich um. Hinzu kommt, dass ich auch als K\u00fcnstler (Clown) f\u00fcr Begeisterung bei den kleinen G\u00e4sten sorgen kann. Alles nat\u00fcrlich auf besonderen Kundenwunsch.<\/p>\n<blockquote><p>Gute Vorbereitung, viel Erfahrung und Technik aus dem Profibereich<\/p><\/blockquote>\n<p><strong>F\u00fcr welche Events eignest du dich als DJ besonders gut?<\/strong><\/p>\n<p>Ich bin musikalisch ein Allrounder. Der Vorteil f\u00fcr jeden Kunden ist, dass ich schon seit vielen Jahren Musik auflege und auch sehr schnell merke, worauf G\u00e4ste reagieren und tanzen. Musiktechnisch f\u00e4ngt es an bei den 60er Jahren, aufw\u00e4rts reicht es bis zu den aktuellen Charts.<\/p>\n<h3>Musik, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein musikalisches Repertoire? Welche Titel in deiner Musik-Sammlung spielst du besonders gerne?<\/strong><\/p>\n<blockquote><p>Ein gesunder Mix von Musik ist wichtig<\/p><\/blockquote>\n<p>Angefangen von den 70er, 80er, 90er, 2000er \u00fcber Latino, Rock, Pop bis hin zu den aktuellen Charts. In den letzten 10 Jahren habe ich mich intensiv mit Techno, House, RnB und Dancefloor besch\u00e4ftigt und habe nat\u00fcrlich auch in diesen Bereich sehr viel Musik. Privat h\u00f6re ich gerne aktuelle Charts und die 80er und 90er. Aus jedem Bereich und jedem Genre sollte schlie\u00dflich f\u00fcr jeden etwas dabei sein. Ein gesunder Mix von Musik ist wichtig, um vielen G\u00e4sten gerecht zu werden.<\/p>\n<p><strong>Beschreibe deine technische Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich inklusive DJ-Technik buchen? Arbeitest du mit Schallplatten, CDs oder MP3s?<\/strong><\/p>\n<p>Ich arbeite mit MP3. Ich habe aber auch noch CDs (Anzahl derzeit ca. 5.000 originale CDs, die zuhause liegen). Zudem biete ich ein umfangreiches Lichtpaket und hochwertige Lautsprecherboxen an. Au\u00dferdem stelle ich auf Kundenwunsch zus\u00e4tzlich eine Seifenblasen- oder eine Nebelmaschine,<br \/>\nScanner, Laser und Traversen zur Verf\u00fcgung. Ob f\u00fcr 50 G\u00e4ste oder 500 G\u00e4ste. Und f\u00fcr die Tontechnik habe ich ein technisches Back Up. Zus\u00e4tzlich habe ich immer ein zweites Laptop aufgestellt und angeschlossen. Sollte etwas nicht mehr funktionieren, geht die Party dank Back Up trotzdem weiter.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als DJ mit?<\/strong><\/p>\n<blockquote><p>Leidenschaft und Professionalit\u00e4t sind das Wichtigste<\/p><\/blockquote>\n<p>Mein Motto ist: \u201cJede Party steht und f\u00e4llt mit der Musik!\u201d, au\u00dferdem mit einer guten Vorbereitung und Umsetzung am Eventtag beim Kunden. Ich bin jemand, der alles gibt. Leidenschaft und Professionalit\u00e4t sind das Wichtigste. Da steckt viel Zeit und Engagement dahinter und das ist auch das, was Kunden an mir sch\u00e4tzen und mir danken.<\/p>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem DJ f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<p>Der Vorteil ist, das Kunden bei evely.com schon vorab viele Informationen \u00fcber einen DJ bekommen. Angefangen vom Preis \u00fcber die Bewertungen und die Technik bis zur Musikauswahl. Wichtig f\u00fcr Kunden ist es, darauf zu achten: Passt die Musikauswahl zu uns und unserer Feier?<br \/>\nUnd welche Erfahrung hat der DJ gesammelt? Was bietet er an Technik an? Neben guten Bewertungen sollte auch eine gewisse Sympathie da sein.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<blockquote><p>Ich versuche, viel \u00fcber den Kunden und sein Event zu erfahren<\/p><\/blockquote>\n<p>Nach der ersten Kontaktaufnahme durch den Kunden rufe ich ihn an und versuche vorab zu kl\u00e4ren, was der Kunde w\u00fcnscht. In den meisten F\u00e4llen kl\u00e4re ich das aber in einem pers\u00f6nlichem Gespr\u00e4ch mit dem Kunden.Wichtig zu wissen ist, was genau w\u00fcnscht der Kunde? Dazu habe ich eine Musik- und Eventcheckliste erstellt, die ich zusammen mit jedem Kunden bespreche.Wichtig ist, zu kl\u00e4ren, was m\u00f6chte der Kunde und was m\u00f6chte er nicht.<br \/>\nDar\u00fcber hinaus versuche ich, viel \u00fcber den Kunden und sein Event zu erfahren.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich einen gelungenen Auftritt aus?<\/strong><\/p>\n<p>Wenn ich es schaffe, dass der Veranstalter und seine G\u00e4ste zufrieden nach Hause gehen. Die G\u00e4ste sollten Spa\u00df haben und sagen, der DJ und seine Musik waren super.<\/p>\n<blockquote><p>Die G\u00e4ste sollten Spa\u00df haben<\/p><\/blockquote>\n<p><strong>Wie reagierst du, wenn z. B. ein Gast betrunken neben dir steht und st\u00e4ndig in dein Mischpult greift oder G\u00e4ste sich denselben Song zum x-ten Mal am Abend w\u00fcnschen?<\/strong><\/p>\n<p>Ich weise ihn h\u00f6flich darauf hin, dass er nichts an der technischen Anlage zu suchen hat und das bitte unterlassen m\u00f6chte. Im Notfall informiere ich den Veranstalter oder Verantwortlichen. Bei doppelt gespielten Musiktiteln oder W\u00fcschen sprechen ich mit dem Veranstalter ab, ob mehrfach ein Lied gespielt werden darf.<\/p>\n<p><strong>Ist schon mal bei einem deiner Gigs so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Ich hatte bei einem Event mal einen Feuerwehreinsatz. Ein Rauchmelder war nicht ausgeschaltet. Nicht etwa durch meine Nebelmaschine kam der Alarm ein Raucher rauchte gen\u00fcsslich eine Zigarette, obwohl dort Rauchverbot war. Seidem kl\u00e4re ich m\u00fcndlich und schriftlich ab, dass bei Nutzung einer Nebelmaschine die Rauchmelder ausgeschaltet sind.<\/p>\n<h3>Erfahrung als DJ<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als DJ?<\/strong><\/p>\n<p>Ich habe bei einem Event einen Jugendfreund getroffen, den ich \u00fcber 25 Jahre nicht gesehen habe. Wir haben nun wieder regen Kontakt. Und dass bei einigen Feiern vor Ort ein Heiratsantrag gemacht wurde.<\/p>\n<p><strong>Wie lernt man DJing deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man DJ werden m\u00f6chte?<\/strong><\/p>\n<blockquote><p>Begeisterung und Leidenschaft f\u00fcr Musik und Technik<\/p><\/blockquote>\n<p>Vorab sollte man sich gut informieren: Was macht und braucht ein DJ? Welche Musikrichtungen passen zu mir? Hinzu kommt eine gewisse Anzahl von Musiktiteln, die jeder am Anfang haben sollte. Gut finde ich auch, mal anderen DJs \u00fcber die Schulter zu schauen, um zu lernen. Mal Workshops zu besuchen. Begeisterung und Leidenschaft f\u00fcr Musik und Technik sollten auf jeden Fall vorhanden sein.<\/p>\n<p><strong>Was bedeutet evely.com f\u00fcr dich?<\/strong><\/p>\n<p>evely.com bietet mir die M\u00f6glichkeit, mich Kunden zu pr\u00e4sentieren. F\u00fcr mich ist es eine Plattform, die Transparenz f\u00fcr Kunden bietet. Jeder Kunde hat die M\u00f6glichkeit, DJs zu vergleichen und viele Informationen zu bekommen. Hinzu kommt f\u00fcr mich die perfekte Umsetzung der Homepage.<\/p>\n<p>Hast du Fragen an Udo? Dann hinterlasse einfach einen Kommentar unter diesem Interview.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit seiner langj\u00e4hrigen Erfahrung verspricht Udo seinen Kunden und G\u00e4sten ein umfangreiches Musikrepertoire: &#8220;Mein Musikarchiv wird st\u00e4ndig aktualisiert, zu Veranstaltungen komme ich mit rund 160.000 Titeln. Da wird es nie langweilig!&#8221;. Seine Lichttechnik stammt aus dem Profibereich und genauso wichtig ist f\u00fcr Udo eine gute Vorbereitung. Mit dem folgenden Interview k\u00f6nnt ihr euch einen guten [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2401,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[208,72],"post_status":[],"class_list":["post-2398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","tag-dj-udo","tag-dj-interviews","quellenhinweis-udo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit DJ Udo - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"DJ Udo h\u00e4lt sein Musikrepertoire immer auf aktuellem Stand. &quot;Da wird es nie langweilig&quot;, versichert er seinen Kunden. Hier das ganze Interview mit DJ Udo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit DJ Udo - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"DJ Udo h\u00e4lt sein Musikrepertoire immer auf aktuellem Stand. &quot;Da wird es nie langweilig&quot;, versichert er seinen Kunden. Hier das ganze Interview mit DJ Udo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-16T11:01:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-29T17:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit DJ Udo - EVELY-Blog","description":"DJ Udo h\u00e4lt sein Musikrepertoire immer auf aktuellem Stand. \"Da wird es nie langweilig\", versichert er seinen Kunden. Hier das ganze Interview mit DJ Udo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit DJ Udo - EVELY-Blog","og_description":"DJ Udo h\u00e4lt sein Musikrepertoire immer auf aktuellem Stand. \"Da wird es nie langweilig\", versichert er seinen Kunden. Hier das ganze Interview mit DJ Udo.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2016-03-16T11:01:32+00:00","article_modified_time":"2024-12-29T17:16:07+00:00","og_image":[{"width":420,"height":277,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg","type":"image\/jpeg"}],"author":"Danny","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284"},"author":{"name":"Danny","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506"},"headline":"DJ-Interview mit Udo","datePublished":"2016-03-16T11:01:32+00:00","dateModified":"2024-12-29T17:16:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284"},"wordCount":1277,"commentCount":1,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg","keywords":["DJ Udo","DJ-Interviews"],"articleSection":["DJ-Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284","name":"DJ Interview mit DJ Udo - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg","datePublished":"2016-03-16T11:01:32+00:00","dateModified":"2024-12-29T17:16:07+00:00","description":"DJ Udo h\u00e4lt sein Musikrepertoire immer auf aktuellem Stand. \"Da wird es nie langweilig\", versichert er seinen Kunden. Hier das ganze Interview mit DJ Udo.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2016\/02\/DJ_udo_inhalt_400px.jpg","width":420,"height":277,"caption":"DJ Udo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-udo-284#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Udo"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","caption":"Danny"},"description":"Reisen, Partys, Freunde und Familie sind die wichtigsten Bestandteile in Dannys Leben. Sie ist ein weltoffener Mensch und liebt es, neue Dinge zu entdecken! Neben dem Schreiben von Blog-Artikeln ist sie auch im Service f\u00fcr evely.com t\u00e4tig. Sowohl privat als auch beruflich liebt sie den Kontakt zu Menschen und ist immer neugierig auf andere und neue Meinungen.","url":"https:\/\/www.evely.com\/blog\/author\/danny"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=2398"}],"version-history":[{"count":7,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2398\/revisions"}],"predecessor-version":[{"id":14433,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/2398\/revisions\/14433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/2401"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=2398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=2398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=2398"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=2398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}