{"id":4919,"date":"2017-05-23T12:00:18","date_gmt":"2017-05-23T10:00:18","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=4919"},"modified":"2025-10-03T14:36:09","modified_gmt":"2025-10-03T12:36:09","slug":"viele-buchungen-bekommen","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen","title":{"rendered":"FAQ: Wie ihr als Dienstleister besonders viele Buchungen bekommt &#8211; 4 Tipps"},"content":{"rendered":"<p class=\"tdfocus-1759494288659\">Ein professionelles und aussagekr\u00e4ftiges Profil auf EVELY.com ist euer Aush\u00e4ngeschild und entscheidet dar\u00fcber, wie oft ihr gebucht werdet. Deshalb ist eine gute Profil-Qualit\u00e4t das A und O f\u00fcr viele Buchungen und letztendlich f\u00fcr euren Erfolg. Interessierte Kunden schauen sich euer DJ-Profil sehr genau an, vergleichen es mit denen eurer Kollegen und entscheiden auf dieser Basis, ob sie eine Buchungsanfrage t\u00e4tigen oder nicht. Daf\u00fcr sollten die Angaben stets aktuell, \u00fcbersichtlich und transparent sein und bei potenziellen Kunden ein sicheres und zufriedenes Gef\u00fchl hinterlassen.<\/p>\n<h2 class=\"tdfocus-1759494353517\">Das optimale Profil<\/h2>\n<p class=\"tdfocus-1759494356172\">Wie ihr als Anbieter euer Profil attraktiv gestaltet und was ihr dabei beachten solltet, haben wir euch bereits in unserem Blog-Artikel <a class=\"tdfocus-1759494360367\" href=\"https:\/\/www.evely.com\/blog\/anbieter\/dj\/tipps\/faq-dj-profil-bearbeiten\">&#8220;FAQ &#8211; Wie \u00e4nderst du dein Profil auf evely.com&#8221;<\/a> ausf\u00fchrlich beschrieben. Au\u00dferdem findet ihr in eurem Login-Bereich unter der Rubrik &#8220;Infos und Angebote&#8221; eine Datei mit vielen Tipps und Hiweisen zur Profiloptimierung.<\/p>\n<p class=\"tdfocus-1759494366764\">Um euch ein Beispiel eines unserer besonders erfolgreichen DJs zu geben, stellen wir euch heute ein aus unserer Sicht optimales Profil vor: Robin aus Nordrhein-Westfalen. Warum wir euch dieses DJ-Profil genauer vorstellen m\u00f6chten und welche Tipps Robin zur Profiloptimierung hat, lest ihr im Folgenden.<\/p>\n<h2>Beispiel: das erfolgreiche DJ-Profil von Robin<\/h2>\n<p class=\"tdfocus-1759494380383\">Robin ist nun seit 1,5 Jahren bei EVELY.com als DJ registriert und wurde bereits \u00fcber 50 mal gebucht. Diese hohe Buchungsquote f\u00fchrt letztendlich auf sein professionelles DJ-Profil und nat\u00fcrlich auch seine verwantwortungsvolle Arbeitsweise zur\u00fcck. Wir haben mit Robin ein kurzes Interview gef\u00fchrt und zeigen euch neben seinen Antworten, welche Angaben und Einstellungen sein Profil so professionell machen.<\/p>\n<h3>Wie schaffst du es, so oft gebucht zu werden? Inwiefern hilft dir dein DJ-Profil dabei?<\/h3>\n<blockquote><p>Robin: Ich denke, vielen Kunden ist es wichtig, dass ihr DJ dem Job auf professioneller Ebene nachgeht, sich leidenschaftlich mit Musik befasst und ein breites Serviceangebot hat. All das ist bei mir der Fall und diese Punkte mache ich auch in meinem DJ-Profil deutlich. Der Kunde soll nach dem Lesen das Gef\u00fchl haben, dass er sich bei der Buchung darauf verlassen kann, dass ich als DJ seine Wunschvorstellungen bestm\u00f6glich umsetzen kann und f\u00fcr ihn da bin, wenn er Fragen hat oder Hilfe und Unterst\u00fctzung in seinen Planungen ben\u00f6tigt. Insofern hilft mir mein DJ Profil unheimlich dabei, Kundeninteresse zu generieren, da ich hier die Chance habe, dem Kunden mich, meine F\u00e4higkeiten, meine Referenzen und mein Angebot transparent zu pr\u00e4sentieren. Ein gro\u00dfes Plus sind nat\u00fcrlich auch die <a href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/dj-bewertung\">Kundenbewertungen<\/a>, die vielen Kunden garantiert als Entscheidungshilfe dienen.<\/p><\/blockquote>\n<h2>TIPP 1:<\/h2>\n<p class=\"tdfocus-1759494729678\">Das Musikangebot von Robin: Er achtet darauf, musikalische Schwerpunkte zu setzen und dem Kunden damit deutlich zu machen, wo seine St\u00e4rken liegen. Auch wenn man als DJ bestimmte Musikrichtungen nicht anbieten kann oder m\u00f6chte, sollte man dies an dieser Stelle deutlich machen. Es ist f\u00fcr einen Kunden durchaus nachvollziehbar, dass ein DJ nicht unbedingt jedes Genre anbieten kann. F\u00fcr manche Kunden ist es sogar \u00fcberzeugender, wenn ein DJ ein ungeliebtes Genre gar nicht anbietet, als wenn er angibt in jedem Genre gleich stark aufgestellt zu sein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-16205\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen-700x309.jpg\" alt=\"\" width=\"700\" height=\"309\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen-700x309.jpg 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen-1200x530.jpg 1200w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen-768x339.jpg 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen-1536x679.jpg 1536w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/musikrichtungen.jpg 1756w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h2>TIPP 2<\/h2>\n<p>Durch Robins aktuelle Referenzen erkennt der Kunde, dass er stetig gebucht wird. Aktualisiert diese daher regelm\u00e4\u00dfig!<\/p>\n<p class=\"tdfocus-1759494794093\"><a href=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/Referenzen-Robin.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-16206\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen-700x243.jpg\" alt=\"\" width=\"700\" height=\"243\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen-700x243.jpg 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen-1200x417.jpg 1200w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen-768x267.jpg 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen-1536x533.jpg 1536w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/referenzen.jpg 1694w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<h3>Was ist das Besondere an deinem DJ-Profil? Worauf achtest du bei den Angaben und Fotos?<\/h3>\n<blockquote><p>Robin: Ich achte darauf, dass der Kunde das Gef\u00fchl bekommt, sich hundertprozentig auf mich verlassen zu k\u00f6nnen. Au\u00dferdem kann ich in meinem Profil pr\u00e4sentieren, welche besonderen Erfahrungen ich in meinem Leben als DJ bereits machen durfte. Ich hatte bereits mehrmals das Vergn\u00fcgen, vor mehreren tausend Leuten zu spielen, und w\u00e4hrend dies auf der einen Seite besondere Momente f\u00fcr mich sind, zeigen diese Referenzen dem Kunden, dass ich selbst den extremsten Situationen gewachsen bin und er mir musikalisch voll vertrauen kann. Bei Fotos achte ich darauf, m\u00f6glichst viel von mir zu pr\u00e4sentieren. Der Kunde soll mich als Person deutlich erkennen, einen Eindruck von meiner Technik erhalten und sehen, dass ich mit meiner Musik die Masse begeistern kann.<\/p><\/blockquote>\n<h2>TIPP 3:<\/h2>\n<p class=\"tdfocus-1759494861278\">Auf dem Profilbild ist Robin w\u00e4hrend der Arbeit zu sehen und gut zu erkennen. Zudem zeigt er auch ein Foto von seiner DJ-Technik und einer seiner Veranstaltungen. Im Profiltext macht er deutlich, was der Kunde erwarten kann, wenn er ihn als DJ bucht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-16207\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich-700x390.jpg\" alt=\"\" width=\"700\" height=\"390\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich-700x390.jpg 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich-1200x669.jpg 1200w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich-768x428.jpg 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich-1536x857.jpg 1536w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/ueber-mich.jpg 1920w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3>Was empfiehlst du anderen DJs bei <a href=\"http:\/\/evely.com\" target=\"_blank\" rel=\"noopener nofollow\">EVELY.com<\/a>, die ihr Profil erfolgreicher machen wollen?<\/h3>\n<blockquote><p>Robin: Macht euch Gedanken dar\u00fcber, was ihr dem Kunden \u00fcber euch mitteilen wollt. Was k\u00f6nnt ihr dem Kunden bieten? Was macht euch anderen DJs gegen\u00fcber so besonders? Wieso kann der Kunde euch vertrauen, dass ihr seine Erwartungen erf\u00fcllt oder gar \u00fcberbietet? All diese Fragen gilt es, bereits im DJ-Profil zu beantworten, denn die Auswahl an DJs ist gro\u00df und die Konkurrenz schl\u00e4ft nicht. Macht auch unbedingt professionelle Bilder, auf denen man euch deutlich erkennt, und passt eure Preisstruktur realistisch euren Gegebenheiten an.<\/p><\/blockquote>\n<h2>TIPP 4:<\/h2>\n<p class=\"tdfocus-1759494950010\">Die tollen Bewertungen zeigen, dass die Kunden auch nach der Veranstaltung von Robin begeistert sind. Bewertungen sind bei der DJ-Suche sehr wichtig, also animiert eure Kunden, diese nach der Veranstaltung abzugeben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-16208\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/bewertungen-1-700x616.jpg\" alt=\"\" width=\"700\" height=\"616\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/bewertungen-1-700x616.jpg 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/bewertungen-1-1200x1056.jpg 1200w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/bewertungen-1-768x676.jpg 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/bewertungen-1.jpg 1364w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Wir k\u00f6nnen uns den Empfehlungen von Robin nur anschlie\u00dfen und danken ihm an dieser Stelle f\u00fcr das Interview.<\/p>\n<p>Wenn ihr Fragen zu eurem DJ-Profil habt, k\u00f6nnt ihr euch gerne per E-Mail an <span \n                data-original-string='ryK44eaXIrQWDYraeYK1Ow==b5cyVZWoeI9CyW08my+prZv8WMjrXltTFt0AaesmRBqDwA='\n                class='apbct-email-encoder'\n                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>se*****@***ly.com<\/span> wenden. Ansonsten w\u00fcnschen wir euch viel Spa\u00df beim Aufpeppen eures Profils und den vielen darauf folgenden Buchungen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein professionelles und aussagekr\u00e4ftiges Profil auf EVELY.com ist euer Aush\u00e4ngeschild und entscheidet dar\u00fcber, wie oft ihr gebucht werdet. Deshalb ist eine gute Profil-Qualit\u00e4t das A und O f\u00fcr viele Buchungen und letztendlich f\u00fcr euren Erfolg. Interessierte Kunden schauen sich euer DJ-Profil sehr genau an, vergleichen es mit denen eurer Kollegen und entscheiden auf dieser Basis, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":16203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[242],"tags":[10,482,238],"post_status":[],"class_list":["post-4919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faq","tag-buchung","tag-dj-robinho","tag-dj-profil","quellenhinweis-EVELY-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>So bekommt ihr besonders viele Buchungen auf evely.com - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Ein professionelles DJ-Profil ist das Aush\u00e4ngeschild jedes DJs bei evely.com. Wie ihr dadurch mehr Buchungen bekommt, zeigen wir euch in 4 Tipps.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So bekommt ihr besonders viele Buchungen auf evely.com - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Ein professionelles DJ-Profil ist das Aush\u00e4ngeschild jedes DJs bei evely.com. Wie ihr dadurch mehr Buchungen bekommt, zeigen wir euch in 4 Tipps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-23T10:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T12:36:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So bekommt ihr besonders viele Buchungen auf evely.com - EVELY-Blog","description":"Ein professionelles DJ-Profil ist das Aush\u00e4ngeschild jedes DJs bei evely.com. Wie ihr dadurch mehr Buchungen bekommt, zeigen wir euch in 4 Tipps.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen","og_locale":"de_DE","og_type":"article","og_title":"So bekommt ihr besonders viele Buchungen auf evely.com - EVELY-Blog","og_description":"Ein professionelles DJ-Profil ist das Aush\u00e4ngeschild jedes DJs bei evely.com. Wie ihr dadurch mehr Buchungen bekommt, zeigen wir euch in 4 Tipps.","og_url":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2017-05-23T10:00:18+00:00","article_modified_time":"2025-10-03T12:36:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg","type":"image\/jpeg"}],"author":"Danny","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen"},"author":{"name":"Danny","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506"},"headline":"FAQ: Wie ihr als Dienstleister besonders viele Buchungen bekommt &#8211; 4 Tipps","datePublished":"2017-05-23T10:00:18+00:00","dateModified":"2025-10-03T12:36:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen"},"wordCount":914,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg","keywords":["Buchung","DJ Robinho","DJ-Profil"],"articleSection":["FAQ"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen","url":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen","name":"So bekommt ihr besonders viele Buchungen auf evely.com - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg","datePublished":"2017-05-23T10:00:18+00:00","dateModified":"2025-10-03T12:36:09+00:00","description":"Ein professionelles DJ-Profil ist das Aush\u00e4ngeschild jedes DJs bei evely.com. Wie ihr dadurch mehr Buchungen bekommt, zeigen wir euch in 4 Tipps.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2017\/05\/viele-buchungen.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/viele-buchungen-bekommen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"FAQ: Wie ihr als Dienstleister besonders viele Buchungen bekommt &#8211; 4 Tipps"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","caption":"Danny"},"description":"Reisen, Partys, Freunde und Familie sind die wichtigsten Bestandteile in Dannys Leben. Sie ist ein weltoffener Mensch und liebt es, neue Dinge zu entdecken! Neben dem Schreiben von Blog-Artikeln ist sie auch im Service f\u00fcr evely.com t\u00e4tig. Sowohl privat als auch beruflich liebt sie den Kontakt zu Menschen und ist immer neugierig auf andere und neue Meinungen.","url":"https:\/\/www.evely.com\/blog\/author\/danny"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/4919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=4919"}],"version-history":[{"count":23,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/4919\/revisions"}],"predecessor-version":[{"id":16209,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/4919\/revisions\/16209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/16203"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=4919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=4919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=4919"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=4919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}