{"id":6116,"date":"2018-01-25T11:57:26","date_gmt":"2018-01-25T10:57:26","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=6116"},"modified":"2025-07-14T13:03:05","modified_gmt":"2025-07-14T11:03:05","slug":"dj-uwe-1596","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596","title":{"rendered":"DJ-Interview mit Uwe"},"content":{"rendered":"<p>Uwes musikalische Pr\u00e4ferenzen liegen bei alten und neuen Schlagern, Stimmungsmusik, Charts und Musik der 70er. Aber nat\u00fcrlich hat er auch andere Musikgenres im Repertoire. Durch seine langj\u00e4hrige DJ-Erfahrung wei\u00df Uwe, wie er die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karnevalspartys gezielt einsetzt. Dabei l\u00e4sst er auch immer gerne die Musikw\u00fcnsche der G\u00e4ste einflie\u00dfen. Uwe legt als <a href=\"https:\/\/www.evely.com\/dj-nrw.html\">DJ in Nordrhein-Westfalen<\/a> auf. Zu finden ist er z. B. als <a href=\"https:\/\/www.evely.com\/dj-koeln.html\">DJ in K\u00f6ln<\/a>, <a href=\"https:\/\/www.evely.com\/dj-bonn.html\">Bonn<\/a> und <a href=\"https:\/\/www.evely.com\/dj-duesseldorf.html\">D\u00fcsseldorf<\/a>.<\/p>\n<h2>Uwe \u00fcber sich selbst, Musik und DJing<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du DJ geworden und was fasziniert dich an dem Job?<\/strong><\/p>\n<p>Also, Musik habe ich schon als Kind unheimlich gerne geh\u00f6rt und alle Hitparaden verfolgt, die es gibt. Ich habe in Discos auch wahnsinnig gerne Leute beim Tanzen beobachtet. Zum DJing bin ich dann eigentlich zuf\u00e4llig gekommen. Anfang der 90er Jahre haben ein Kumpel von mir und ich eigentlich nur aus Spa\u00df in einer Kneipe im K\u00f6lner Friesenviertel angefangen, Musik aufzulegen. Das waren kommerzielle Musik und Schlager der 70er Jahre. Das haben wir selbstironisch &#8220;Bad Taste&#8221; genannt, weil dies zu dieser Zeit v\u00f6llig out war. Vielleicht gerade deswegen wurde das dort zum Szeneevent. Mit den Jahren habe ich mir dann auch alle anderen kommerziellen Musikstile angeeignet und lege heute bei den unterschiedlichsten Events auf.<\/p>\n<p><strong>Was macht dich als DJ unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<blockquote><p>Ich ber\u00fccksichtige sehr stark die Musikw\u00fcnsche der Gastgeber<\/p><\/blockquote>\n<p>Ich glaube, dass ich sehr kundenorientiert bin. Das f\u00e4ngt schon bei den <a href=\"https:\/\/www.evely.com\/blog\/anbieter\/dj\/tipps\/10-fragen-dj-vorgespraech\">Vorgespr\u00e4chen<\/a> an und setzt sich bei der eigentlichen Veranstaltung fort. Aus meinen <a href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/dj-bewertung\">Bewertungen<\/a> ergibt sich meines Erachtens auch, dass ich sehr stark die <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/musikwunschbogen-djs-kunden\">Musikw\u00fcnsche der Gastgeber<\/a> und der G\u00e4ste ber\u00fccksichtige. Ich glaube auch, &#8211; das hat mir mal jemand attestiert &#8211; dass ich so eine Art Empathie f\u00fcr die G\u00e4ste bzw. f\u00fcr die Leute auf der Tanzfl\u00e4che entwickeln kann.<\/p>\n<p><strong>F\u00fcr welche Events eignest du dich als DJ besonders gut?<\/strong><\/p>\n<p>Da will ich mich eigentlich gar nicht so festlegen. Ich lege viel auf Geburtstagen und <a href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/kosten-dj-hochzeit\">Hochzeiten<\/a> auf. Aber ich bin auch schon seit Ewigkeiten im <a href=\"https:\/\/www.evely.com\/blog\/kunden\/party-planen\/faschings-karnevals-party-musik-planung\">Karneval<\/a> unterwegs. Meine St\u00e4rke liegt gerade in den Veranstaltungen, bei denen es eben nicht nur auf eine Musikrichtung ankommt, sondern ein sehr abwechslungsreiches Programm erforderlich ist.<\/p>\n<h3>Musik, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein musikalisches Repertoire? Welche Titel in deiner Musik-Sammlung spielst du besonders gerne?<\/strong><\/p>\n<p>Also, ich bin eigentlich in jeder kommerziellen Musikrichtung zu Hause. Das mache ich dann immer von den G\u00e4sten abh\u00e4ngig. Bestes Beispiel ist z. B. &#8220;Atemlos&#8221; von Helene Fischer, bei machen Veranstaltungen immer noch ein Muss, bei anderen ein No-Go. Aber es gibt nat\u00fcrlich ein paar <a href=\"https:\/\/www.evely.com\/blog\/kunden\/partymusik\/evergreens\">Klassiker<\/a>, die eigentlich immer ankommen, z. B. &#8220;Everybody&#8221; von den Backstreetboys, &#8220;Y.M.C.A.&#8221;, &#8220;Ain`t nobody&#8221; von Chaka Khan oder &#8220;Macarena&#8221;.<\/p>\n<blockquote><p>Ich bin in jeder kommerziellen Musikrichtung zu Hause.<\/p><\/blockquote>\n<p><strong><span class=\"im\">Beschreibe deine technische Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich inklusive DJ-Technik buchen? Arbeitest du mit Schallplatten, CDs oder MP3s?<\/span><\/strong><\/p>\n<p>Ich lege mit Laptop und dem professionellen <a href=\"https:\/\/www.evely.com\/blog\/anbieter\/dj\/technik\/digital-djing-dj-software\">DJ-Programm<\/a> Traktor Pro auf. F\u00fcr den absoluten Worst-Case eines Laptop-Absturzes (was zum Gl\u00fcck noch nie passiert ist) bringe ich noch CDs als Backup mit. D. h., es wird immer f\u00fcr Musik gesorgt sein. Gerade die Songs, die aus Sicht der Gastgeber gar nicht fehlen d\u00fcrfen, habe ich auch nochmal zus\u00e4tzlich auf CD.<\/p>\n<p>Ansonsten ist mir beim Equipment sehr wichtig, dass die Musik laut immer noch gut klingt. Daher habe ich einen hochwertigen Mischer und anspruchsvolle Fullrangeboxen der Marke RCF. Nat\u00fcrlich sind in meinem Paket auch immer noch Licht und ein Funkmikrofon enthalten.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als DJ mit?<\/strong><\/p>\n<blockquote><p>Ich habe ein profundes Musikwissen.<\/p><\/blockquote>\n<p>Da ich, wie oben erw\u00e4hnt, fast jede Musikrichtung gut finde, habe ich nicht nur ein profundes Musikwissen. Ich bin auch sehr vielseitig und kann jederzeit jede musikalische Richtung einschlagen. Ich entscheide oft erst beim laufenden Song, was als n\u00e4chstes gespielt wird.<\/p>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem DJ f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<p>Es muss in allem einfach deutlich werden, dass der DJ mit Herzblut und Leidenschaft dabei ist. Ich biete z. B. immer Open-End an, weil es doch Ziel des DJ sein muss, dass es m\u00f6glichst lange geht. Das ist doch ein Qualit\u00e4tsmerkmal. Ich mag DJs nicht, die st\u00e4ndig auf die Uhr gucken oder gar solche Regeln wie eine U-10-Klausel haben, d. h., unter 10 Personen spielen sie gar nicht weiter. Das kann ich z. B. nicht verstehen.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<blockquote><p>Der Kunde muss das Gef\u00fchl haben, bei mir gut aufgehoben zu sein.<\/p><\/blockquote>\n<p>Zum einen ist mir ein ausf\u00fchrliches Kundengespr\u00e4ch sehr wichtig. Der Kunde muss das Gef\u00fchl haben, bei mir gut aufgehoben zu sein. Umgekehrt pr\u00fcfe ich f\u00fcr mich aber auch, ob ich die W\u00fcnsche des Kunden wirklich zu 100 Prozent bedienen kann. Zuletzt habe ich tats\u00e4chlich einem Kunden angeraten, sich einen anderen DJ bei EVELY zu suchen, weil ich dessen Vorstellungen nicht komplett entsprechen konnte. Und ich bereite mich sehr genau nach den jeweiligen Musikw\u00fcnschen der Gastgeber im Vorfeld vor.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich einen gelungenen Auftritt aus?<\/strong><\/p>\n<blockquote><p>Wenn die Gastgeber und die G\u00e4ste es super fanden.<\/p><\/blockquote>\n<p>Da ich sehr kundenorientiert bin: Wenn die Gastgeber und die G\u00e4ste es super fanden. Nur als Beispiel: Einmal ist ein P\u00e4rchen aus einem bestellten und somit schon angezahlten Taxi wieder ausgestiegen, weil sie sich nicht von der Musik trennen konnten.<\/p>\n<p><strong>Was ist das Schlimmste, das ein Gast einem DJ antun kann? F\u00fcnfmal hintereinander \u201eAtemlos\u201c w\u00fcnschen, ins Mischpult greifen, \u2026?<\/strong><\/p>\n<p>Also, die meisten G\u00e4ste sind ja nett und \u00e4u\u00dfern h\u00f6flich ihre Musikw\u00fcnsche. Dem komme ich dann auch gerne nach. Schwierigkeiten hatte ich zum Gl\u00fcck nur einige wenige Male. Da haben sich die jeweiligen Personen nicht nur im Tonfall vergriffen. Der Song, der kritisiert wurde, kam auch noch gut an. Ich versuche dann immer, darauf h\u00f6flich aber bestimmt zu reagieren.<\/p>\n<p><strong>Ist schon mal bei einem deiner Gigs so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Zum Gl\u00fcck ist bisher noch nicht wirklich was schiefgegangen. Einmal hat das DJ-Programm gehakt. Da habe ich dann aber direkt eine CD abgespielt. Das haben die G\u00e4ste noch nicht mal gemerkt.<\/p>\n<h3>Erfahrung als DJ<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als DJ?<\/strong><\/p>\n<p>Das war bei einem 50. Geburtstag bei guten Bekannten von mir. Da wurde der Frau wie im Film ein <a href=\"https:\/\/www.evely.com\/blog\/kunden\/hochzeit-planen\/ideen-heiratsantrag\">Heiratsantrag<\/a> gemacht. Das war nat\u00fcrlich ein Highlight.<\/p>\n<p><strong><span class=\"im\">Wie lernt man DJing deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man DJ werden m\u00f6chte?<\/span><\/strong><\/p>\n<blockquote><p>Ein DJ sollte sich als Dienstleister verstehen.<\/p><\/blockquote>\n<p>Das ist schwer zu beantworten, weil es so viele verschiedene Arten von DJs gibt. Ein DJ, der auf Veranstaltungen wie Hochzeiten, Geburtstagen etc. auflegt, sollte ein umfangreiches Musikwissen und vielseitiges Musikrepertoire mitbringen. Im Gegensatz beispielsweise zu einem Club-DJ sollte man sich auf Hochzeiten oder \u00e4hnlichen Veranstaltungen auf jeden Fall auch als Dienstleister verstehen, der die Gastgeber dabei unterst\u00fctzt, dass es f\u00fcr sie ein im positiven Sinne unvergesslicher Abend wird.<\/p>\n<p><strong>Was bedeutet evely.com f\u00fcr dich?<\/strong><\/p>\n<p>EVELY hat mir dabei geholfen, nach einer gewissen Pause im DJing wieder Kundenkontakte zu bekommen. Denn diese Kontakte ben\u00f6tig man, um wieder reinzukommen. Ich finde aber auch, dass EVELY ein sehr sch\u00f6nes, transparentes Portal f\u00fcr Kunden ist, wovon wiederum dann auch die DJs profitieren.<\/p>\n<h2>Habt ihr Fragen an Uwe?<\/h2>\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uwes musikalische Pr\u00e4ferenzen liegen bei alten und neuen Schlagern, Stimmungsmusik, Charts und Musik der 70er. Aber nat\u00fcrlich hat er auch andere Musikgenres im Repertoire. Durch seine langj\u00e4hrige DJ-Erfahrung wei\u00df Uwe, wie er die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karnevalspartys gezielt einsetzt. Dabei l\u00e4sst er auch immer gerne die Musikw\u00fcnsche der G\u00e4ste [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[192,72],"post_status":[],"class_list":["post-6116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","tag-dj-uwe","tag-dj-interviews","quellenhinweis-dj-uwe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit DJ Uwe - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Dank langj\u00e4hriger DJ-Erfahrung und einem gro\u00dfen Musikrepertoire setzt DJ Uwe die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karneval gezielt ein. Hier lest ihr unser Interview mit DJ Uwe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit DJ Uwe - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Dank langj\u00e4hriger DJ-Erfahrung und einem gro\u00dfen Musikrepertoire setzt DJ Uwe die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karneval gezielt ein. Hier lest ihr unser Interview mit DJ Uwe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-25T10:57:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T11:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"891\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit DJ Uwe - EVELY-Blog","description":"Dank langj\u00e4hriger DJ-Erfahrung und einem gro\u00dfen Musikrepertoire setzt DJ Uwe die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karneval gezielt ein. Hier lest ihr unser Interview mit DJ Uwe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit DJ Uwe - EVELY-Blog","og_description":"Dank langj\u00e4hriger DJ-Erfahrung und einem gro\u00dfen Musikrepertoire setzt DJ Uwe die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karneval gezielt ein. Hier lest ihr unser Interview mit DJ Uwe.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2018-01-25T10:57:26+00:00","article_modified_time":"2025-07-14T11:03:05+00:00","og_image":[{"width":891,"height":870,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg","type":"image\/jpeg"}],"author":"Danny","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596"},"author":{"name":"Danny","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506"},"headline":"DJ-Interview mit Uwe","datePublished":"2018-01-25T10:57:26+00:00","dateModified":"2025-07-14T11:03:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596"},"wordCount":1296,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg","keywords":["DJ Uwe","DJ-Interviews"],"articleSection":["DJ-Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596","name":"DJ Interview mit DJ Uwe - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg","datePublished":"2018-01-25T10:57:26+00:00","dateModified":"2025-07-14T11:03:05+00:00","description":"Dank langj\u00e4hriger DJ-Erfahrung und einem gro\u00dfen Musikrepertoire setzt DJ Uwe die passende Musik auf Feiern wie Geburtstagen, Hochzeiten, Firmenfeiern und Karneval gezielt ein. Hier lest ihr unser Interview mit DJ Uwe.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/01\/IMG_7253-e1516627186786.jpg","width":891,"height":870,"caption":"DJ Uwe"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-uwe-1596#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Uwe"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/66149455d9fe8d6977526df66bc48506","name":"Danny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55d492af129296d2e1e7a4e4f7c0fb515a103296f39c94b4b118166919d0edb7?s=96&d=mm&r=g","caption":"Danny"},"description":"Reisen, Partys, Freunde und Familie sind die wichtigsten Bestandteile in Dannys Leben. Sie ist ein weltoffener Mensch und liebt es, neue Dinge zu entdecken! Neben dem Schreiben von Blog-Artikeln ist sie auch im Service f\u00fcr evely.com t\u00e4tig. Sowohl privat als auch beruflich liebt sie den Kontakt zu Menschen und ist immer neugierig auf andere und neue Meinungen.","url":"https:\/\/www.evely.com\/blog\/author\/danny"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=6116"}],"version-history":[{"count":5,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6116\/revisions"}],"predecessor-version":[{"id":15485,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6116\/revisions\/15485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/6118"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=6116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=6116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=6116"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=6116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}