{"id":6865,"date":"2018-07-10T11:24:43","date_gmt":"2018-07-10T09:24:43","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=6865"},"modified":"2025-10-02T17:02:29","modified_gmt":"2025-10-02T15:02:29","slug":"klimaneutralitaet-evely","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely","title":{"rendered":"Klimaneutralit\u00e4t: EVELY engagiert sich gegen vermehrte CO\u00b2-Emissionen"},"content":{"rendered":"<p>Was hat EVELY mit dem Klima zu tun? Produzieren DJs etwa CO\u00b2? Die kurze Antwort lautet: Ja, das l\u00e4sst sich leider kaum vermeiden. Aus diesem Grund haben wir von EVELY uns dazu entschieden, uns f\u00fcr einen Klimaausgleich einzusetzen.<\/p>\n<p>In diesem Artikel erfahrt ihr, was der Klimabeitrag ist und wie wir von EVELY damit Klimaschutzprojekte unterst\u00fctzen.<\/p>\n<h2>Was ist ein Klimabeitrag?<\/h2>\n<p>Bei den meisten Unternehmen wird an irgendeiner Stelle im Arbeits-, Produktions- oder Transportprozess CO\u00b2 (Kohlenstoffdioxid) ausgesto\u00dfen. Das Gas CO\u00b2 ist eigentlich ein nat\u00fcrlicher Luftbetandteil, das jedoch zus\u00e4tzlich z. B. beim Betrieb von Maschinen und beim Fahren mit Lkw und Pkw entsteht und so in unnat\u00fcrlich hohen Mengen in die Erdatmosph\u00e4re gelangt.<\/p>\n<p>Das Problem an einem zu hohen CO\u00b2-Anteil in der Atmosph\u00e4re ist, dass er den Treibhauseffekt und damit die globale Klimaerw\u00e4rmung verst\u00e4rkt. Aus diesem Grund haben es sich mittlerweile einige Organisationen wie <a href=\"https:\/\/www.atmosfair.de\/de\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">atmosfair<\/a> oder\u00a0<a href=\"https:\/\/www.myclimate.org\/de\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">myclimate<\/a> auf die Fahnen geschrieben, zertifizierte Klimaschutzprojekte durchzuf\u00fchren und den CO\u00b2-Aussto\u00df weltweit zu kompensieren.<\/p>\n<p>\u00dcber einen sogenannten Klimabeitrag k\u00f6nnen sich <strong>Firmen und ihre Kunden finanziell an solchen Klimaschutzprojekten beteiligen<\/strong> und ihrerseits helfen, den CO\u00b2-Aussto\u00df zu kompensieren, der meist automatisch entsteht, wenn etwas f\u00fcr Kunden produziert und an sie geliefert wird oder wenn sie eine Dienstleistung in Anspruch nehmen, die z. B. mit einem Anfahrtsweg durch den Dienstleister verbunden ist.<\/p>\n<h2>Darum hat EVELY den Klimabeitrag eingef\u00fchrt<\/h2>\n<p>Ihr fragt euch, an welcher Stelle bei der Arbeit eines DJs CO\u00b2 produziert wird? Tats\u00e4chlich entsteht der gr\u00f6\u00dfte Teil der Emissionen auf der Fahrt eines DJs zu seinen Auftritten auf Hochzeiten, Geburtstagen, Firmenfeiern &amp; Co. Und da die DJs f\u00fcr solche Auftritte von Kunden auf evely.com gebucht werden, m\u00f6chten wir einen Beitrag zur Kompensation dieser CO\u00b2-Emissionen leisten. Sprich: Die <strong>Klimabelastung durch die Anfahrt des DJs zur Veranstaltung seines Kunden wollen wir durch einen Geldbetrag ausgleichen,<\/strong> den wir an zertifizierte Klimaschutzprojekte weiterleiten, die die entstandene Menge an CO\u00b2-Emissionen kompensieren.<\/p>\n<h2>So beteiligt ihr euch auf evely.com am Klimaschutz<\/h2>\n<p>Da alle EVELY-Kunden mitmachen, k\u00f6nnen tats\u00e4chlich s\u00e4mtliche CO\u00b2-Emissionen ausgeglichen werden, die durch die Anfahrten der gebuchten EVELY-DJs entstehen. Nat\u00fcrlich braucht sich <strong>jeder Kunde nur mit dem Geldbetrag zu beteiligen, der seine gebuchte DJ-Dienstleistung klimaneutral macht<\/strong>. Der notwendige Betrag f\u00fcr jeden einzelnen ist dabei sehr gering.<\/p>\n<p>Eure Beteiligung am Klimabeitrag ist f\u00fcr euch ganz einfach: Sobald ihr euch auf evely.com f\u00fcr einen DJ entschieden habt, wird automatisch im Hintergrund berechnet, wie weit die Strecke ist, die euer Wunsch-DJ zu eurer Location fahren muss. Die <strong>CO\u00b2-Emissionen, die auf der Fahrt zu eurer Veranstaltung entstehen,<\/strong> werden auf diese Weise kilometergenau berechnet, und entsprechend <strong>in einen Geldbetrag umgewandelt,<\/strong> der f\u00fcr die Kompensierung n\u00f6tig ist. Der genaue Geldbetrag wird euch dann im n\u00e4chsten Buchungsschritt als &#8220;inkl. Klimabeitrag: x \u20ac&#8221; angezeigt.<\/p>\n<figure id=\"attachment_16079\" aria-describedby=\"caption-attachment-16079\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16079 size-medium\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-price-700x187.png\" alt=\"\" width=\"700\" height=\"187\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-price-700x187.png 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-price-768x205.png 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-price.png 1200w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-16079\" class=\"wp-caption-text\">Hier k\u00f6nnt ihr euren individuellen Klimabeitrag und den ver\u00e4nderten Komplettpreis sehen.<\/figcaption><\/figure>\n<p class=\"tdfocus-1759417239806\" data-wp-editing=\"1\">\n<p>Ihr <strong>zahlt euren individuellen Klimabeitrag ganz bequem zusammen mit eurem Gesamtbetrag<\/strong> der Buchung am Tag der Veranstaltung an euren DJ und braucht euch um nichts Weiteres zu k\u00fcmmern. Euer DJ leitet euren Klimabeitrag an uns weiter und wir senden das Geld einmal im Jahr an ein ausgew\u00e4hltes Klimaschutzprojekt.<\/p>\n<h3>Unser Tipp:<\/h3>\n<figure id=\"attachment_16080\" aria-describedby=\"caption-attachment-16080\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16080 size-medium\" src=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-search-700x305.png\" alt=\"\" width=\"700\" height=\"305\" srcset=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-search-700x305.png 700w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-search-768x335.png 768w, https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/eve-search.png 1200w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-16080\" class=\"wp-caption-text\">An diesen beiden Stellen k\u00f6nnt ihr entweder die maximale Fahrtstrecke eures DJs einschr\u00e4nken (s. Markierung oben links) oder die DJs nach Entfernung zu eurer Location filtern (s. Markierung rechts).<\/figcaption><\/figure>\n<p class=\"tdfocus-1759417285365\">Wenn ihr euch <strong>f\u00fcr einen DJ in eurer N\u00e4he entscheidet,<\/strong> ist nat\u00fcrlich seine Anfahrt k\u00fcrzer, so dass durch eure Buchung von vorneherein weniger CO\u00b2 entsteht und auch die Geb\u00fchr f\u00fcr euren Klimabeitrag g\u00fcnstiger wird. Hier seht ihr, wie ihr gezielt nach DJs mit kurzer Anfahrt suchen k\u00f6nnt:<\/p>\n<h2>Wie wird der Klimabeitrag pro DJ-Buchung berechnet?<\/h2>\n<p>Im Folgenden zeigen wir euch, wie euer Betrag f\u00fcr den Klimaausgleich berechnet wird. Der Betrag h\u00e4ngt davon ab, wie weit euer Wunsch-DJ von eurer Event-Location entfernt ist. Grunds\u00e4tzlich gilt: <strong>Pro Buchung zahlen Kunden so derzeit f\u00fcr den Klimaausgleich mindestens 1 Euro, und maximal 6 Euro.<\/strong><\/p>\n<p>Die folgenden Betr\u00e4ge gelten f\u00fcr Einfachstrecken (oneway) und enthalten bereits die Mehrwertsteuer:<\/p>\n<ul>\n<li>bis 50 km Entfernung zur Location = 1 \u20ac<\/li>\n<li>51 &#8211; 100 km Entfernung zur Location = 2 \u20ac<\/li>\n<li>101 &#8211; 150 km Entfernung zur Location = 3 \u20ac<\/li>\n<li>151 &#8211; 200 km\u00a0Entfernung\u00a0zur Location = 4 \u20ac<\/li>\n<li>201 &#8211; 250 km\u00a0Entfernung\u00a0zur Location = 5 \u20ac<\/li>\n<li>251 &#8211; 300 km\u00a0Entfernung\u00a0zur Location = 6 \u20ac<\/li>\n<\/ul>\n<p><strong>Pro 100 Kilometer<\/strong>, die euer DJ also zu eurem Veranstaltungsort insgesamt hin und zur\u00fcck fahren muss,<strong> gen\u00fcgt durchschnittlich also schon 1 \u20ac, um seine CO\u00b2-Belastung f\u00fcr das Klima auszugleichen<\/strong>.<\/p>\n<h2>Was geschieht mit dem Klimabeitrag?<\/h2>\n<p>Wir sammeln das Geld f\u00fcr den Klimaausgleich f\u00fcr ein Jahr und \u00fcberweisen es an dasjenige Klimaschutzprojekt, das unserer Meinung nach den sinnvollsten Beitrag zum Klimaausgleich betreibt. Der gesammelte Betrag wird, nach Abzug der gesetzlich vorgeschriebenen Mehrwertsteuer, komplett gespendet. Wir behalten keinen Anteil f\u00fcr Entwicklung oder Betrieb des Projektes ein.<\/p>\n<p>Zus\u00e4tzlich zum Klimaausgleich ist uns wichtig, dass die Projekte auch den Menschen vor Ort die M\u00f6glichkeit bieten, ihre Situation zu verbessern. Wir denken, nur so kann ein nachhaltiges Bewusstsein f\u00fcr den Klimaschutz entstehen. Die Projekte der dahinterstehenden Organisationen sind mit den strengsten, unabh\u00e4ngigen Qualit\u00e4tsstandards (CDM, Gold Standard und Plan Vivo) f\u00fcr CO\u00b2-Kompensationsprojekte zertifiziert. Dank der Zertifikate ist sichergestellt, dass die Projekte den Anspr\u00fcchen des &#8220;Clean Development Mechanism&#8221; entsprechen.<\/p>\n<p><strong>Am 28. Juni 2019 haben wir die erste gro\u00dfe Spende vorgenommen. Als erstes Klimaschutzprojekt, das wir mit den zwischen Juni 2018 und Juni 2019 gesammelten Klimabeitr\u00e4gen unterst\u00fctzen wollten, haben wir uns f\u00fcr die <a href=\"https:\/\/www.myclimate.org\/de\/klimaschutzprojekte\/projekt\/nicaragua-wald-7186\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Wiederaufforstung in Nicaragua<\/a> der Organistaion <a href=\"https:\/\/www.myclimate.org\/\" target=\"_blank\" rel=\"nofollow\">myclimate<\/a> entschieden. \u00dcber unser unterst\u00fctztes Projekt 2019 und alle folgenden Projekte erfahrt ihr mehr in diesem <a href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/unsere-spenden-fuer-klimaneutralitaet-schutzprojekte-spendensummen-im-ueberblick\">Blog-Artikel<\/a>.<\/strong><\/p>\n<h2>Was haltet ihr vom CO\u00b2-Ausgleich?<\/h2>\n<p>Beteiligt ihr euch bereits am Klimaausgleich oder habt ihr Fragen dazu? Schreibt uns gerne einen Kommentar unter diesen Artikel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was hat EVELY mit dem Klima zu tun? Produzieren DJs etwa CO\u00b2? Die kurze Antwort lautet: Ja, das l\u00e4sst sich leider kaum vermeiden. Aus diesem Grund haben wir von EVELY uns dazu entschieden, uns f\u00fcr einen Klimaausgleich einzusetzen. In diesem Artikel erfahrt ihr, was der Klimabeitrag ist und wie wir von EVELY damit Klimaschutzprojekte unterst\u00fctzen. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":16077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[755,756],"post_status":[],"class_list":["post-6865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ueber-uns","tag-klimaausgleich","tag-klimaneutral","quellenhinweis-EVELY-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klimaneutralit\u00e4t: EVELY engagiert sich - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Wie wir von evely.com uns als Unternehmen f\u00fcr den Ausgleich vermehrter CO\u00b2-Emissionen engagieren und wie Kunden sich an der Aktion beteiligen k\u00f6nnen, lest ihr jetzt bei uns im Blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klimaneutralit\u00e4t: EVELY engagiert sich - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Wie wir von evely.com uns als Unternehmen f\u00fcr den Ausgleich vermehrter CO\u00b2-Emissionen engagieren und wie Kunden sich an der Aktion beteiligen k\u00f6nnen, lest ihr jetzt bei uns im Blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-10T09:24:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T15:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stefanie\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klimaneutralit\u00e4t: EVELY engagiert sich - EVELY-Blog","description":"Wie wir von evely.com uns als Unternehmen f\u00fcr den Ausgleich vermehrter CO\u00b2-Emissionen engagieren und wie Kunden sich an der Aktion beteiligen k\u00f6nnen, lest ihr jetzt bei uns im Blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely","og_locale":"de_DE","og_type":"article","og_title":"Klimaneutralit\u00e4t: EVELY engagiert sich - EVELY-Blog","og_description":"Wie wir von evely.com uns als Unternehmen f\u00fcr den Ausgleich vermehrter CO\u00b2-Emissionen engagieren und wie Kunden sich an der Aktion beteiligen k\u00f6nnen, lest ihr jetzt bei uns im Blog.","og_url":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2018-07-10T09:24:43+00:00","article_modified_time":"2025-10-02T15:02:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg","type":"image\/jpeg"}],"author":"Stefanie","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely"},"author":{"name":"Stefanie","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/390b92b744f07dbbcad5d7ae47fa3764"},"headline":"Klimaneutralit\u00e4t: EVELY engagiert sich gegen vermehrte CO\u00b2-Emissionen","datePublished":"2018-07-10T09:24:43+00:00","dateModified":"2025-10-02T15:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely"},"wordCount":992,"commentCount":4,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg","keywords":["Klimaausgleich","klimaneutral"],"articleSection":["\u00dcber uns"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely","url":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely","name":"Klimaneutralit\u00e4t: EVELY engagiert sich - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg","datePublished":"2018-07-10T09:24:43+00:00","dateModified":"2025-10-02T15:02:29+00:00","description":"Wie wir von evely.com uns als Unternehmen f\u00fcr den Ausgleich vermehrter CO\u00b2-Emissionen engagieren und wie Kunden sich an der Aktion beteiligen k\u00f6nnen, lest ihr jetzt bei uns im Blog.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2018\/07\/co2-3139230_1920.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/ueber-uns\/klimaneutralitaet-evely#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Klimaneutralit\u00e4t: EVELY engagiert sich gegen vermehrte CO\u00b2-Emissionen"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/390b92b744f07dbbcad5d7ae47fa3764","name":"Stefanie","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f423f09a453611792bd1539bd21d214d743c10b2a6b7054100fa8c31fee8d771?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f423f09a453611792bd1539bd21d214d743c10b2a6b7054100fa8c31fee8d771?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f423f09a453611792bd1539bd21d214d743c10b2a6b7054100fa8c31fee8d771?s=96&d=mm&r=g","caption":"Stefanie"},"description":"Stefanie liebt das Bloggen und ist immer wieder auf der Suche nach guten Themen. Musikalisch ist sie mittlerweile bei sowas wie Folk-Rock angekommen, Tanzen geht bei ihr aber grunds\u00e4tzlich auf fast alles und gerne auch schon morgens (Lieblings-Spotify-Playlist: Top of the Morning). Zum Feiern ist Stefanie wirklich kein Anlass zu gering :)","url":"https:\/\/www.evely.com\/blog\/author\/stefanie"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=6865"}],"version-history":[{"count":36,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6865\/revisions"}],"predecessor-version":[{"id":16083,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/6865\/revisions\/16083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/16077"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=6865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=6865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=6865"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=6865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}