{"id":8219,"date":"2019-01-17T12:18:31","date_gmt":"2019-01-17T11:18:31","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=8219"},"modified":"2019-05-15T13:15:02","modified_gmt":"2019-05-15T11:15:02","slug":"dj-mika-aida-dj-3206","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206","title":{"rendered":"DJ-Interview mit Manuel"},"content":{"rendered":"<p>Manuel bringt als DJ aus <a href=\"https:\/\/www.evely.com\/dj-baden-wuerttemberg.html\">Baden-W\u00fcrttemberg<\/a> \u00fcber 10 Jahre Erfahrung in dem Job mit und tritt unter anderem in <a href=\"https:\/\/www.evely.com\/dj-augsburg.html\">Augsburg<\/a>, <a href=\"https:\/\/www.evely.com\/dj-nuernberg.html\">N\u00fcrnberg<\/a> und <a href=\"https:\/\/www.evely.com\/dj-mainz.html\">Mainz<\/a> auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, schaut euch unser DJ-Interview mit ihm an. <a href=\"https:\/\/www.evely.com\/djs\/dj-mika-aida-dj-3206.html\">Nat\u00fcrlich k\u00f6nnt ihr Manuel auch direkt hier buchen.<\/a><\/p>\n<h2>Manuel \u00fcber sich selbst &amp; Musik<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du zu deinem Job gekommen und was fasziniert dich daran?<\/strong><\/p>\n<blockquote><p>Ich h\u00f6re nie mehr damit auf.<\/p><\/blockquote>\n<p>Bevor ich lesen und schreiben konnte, konnte ich Noten lesen und schreiben. Schon im Alter von 5 Jahren wurde meine Leidenschaft zur Musik geboren. Als ich mit 14 dann das erste Mal hinter Plattentellern stand, war sofort klar, ich h\u00f6re nie mehr damit auf.<\/p>\n<p><strong>Was macht dich als Dienstleister unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<p>Mit \u00fcber 15 Jahren Erfahrung bringe ich bei \u00fcber 60.000 Titeln f\u00fcr jeden Geschmack immer das Richtige auf die Tanzfl\u00e4che. Weiterhin habe ich durch mein breit gef\u00e4chertes Einsatzgebiet viel Erfahrung sammeln k\u00f6nnen und wei\u00df mit jeder Situation meist perfekt umzugehen.<\/p>\n<p><strong>F\u00fcr welche Events eignest du dich besonders gut?<\/strong><\/p>\n<blockquote><p>Das Wichtigste: dass die G\u00e4ste tanzen und Spa\u00df haben.<\/p><\/blockquote>\n<p>Egal ob Hochzeiten, Geburtstage oder einfach ein Fest zum gegebenen Anlass: Das Wichtigste f\u00fcr mich ist, dass die G\u00e4ste tanzen und Spa\u00df haben.<\/p>\n<h3>Angebot, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein Angebot? Z. B. welche Musik oder Lieder spielst du gerne?<\/strong><\/p>\n<p>Von Oldies der 70er, <a href=\"https:\/\/www.evely.com\/blog\/kunden\/partymusik\/80er-90er-playlist\">80er<\/a>, 90er bis hin zu Top Hits von heute, <a href=\"https:\/\/www.evely.com\/blog\/kunden\/partymusik\/schlager-playlist\">Schlager<\/a>, Latin und Rock-Classics kann ich mein Repertoire nur als breit gef\u00e4chert beschreiben.<\/p>\n<p><strong>Beschreibe deine Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich buchen? Welche Technik, Instrumente etc. bringst du mit?<\/strong><\/p>\n<p>Bei der Sound Technik setze ich schon seit \u00fcber 10 Jahren auf den PA Hersteller D.A.S.. Ich selbst lege meist mit Controller auf, habe mein Handwerk aber auch mit Platten- und CD-Spielern gelernt.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als Dienstleister mit?<\/strong><\/p>\n<div id=\"wkj-833991957\" class=\"wkj-content\">Die perfekte Party des Kunden ist meine Passion. Angefangen wird meist mit meinem Musikfragebogen, der die Genren-Auswahl sehr erleichtert und ein klares Erfolgsrezept von gelungenen Veranstaltungen darstellt. Planung, Umsetzung und Flexibilit\u00e4t bis in die letzte Minute sind weitere St\u00e4rken.<\/div>\n<blockquote><p>Die perfekte Party ist meine Passion.<\/p><\/blockquote>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem Dienstleister wie dir f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<p>Bei der Auswahl des richtigen DJs sollte der <a href=\"https:\/\/www.evely.com\/blog\/ueber-uns\/faq\/was-kostet-ein-dj\">Preis<\/a> erst an dritter Stelle kommen. Davor sollte die Sympathie und die organisatorische Umsetzung passen.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<p>Anhand des Musikfragebogens mache ich mir eine grobe Genre-Sammlung f\u00fcr den Abend fertig. Beim Thema Anlage, Dekoration und Licht schau ich mir immer zuerst die Location an und spreche dann in einem pers\u00f6nlichen Treffen oder Telefonat Empfehlungen aus, die ich mit Bildern erl\u00e4utere, denn Bilder sagen bekanntlich mehr als tausend Worte.<\/p>\n<blockquote><p>Ich spreche in einem pers\u00f6nlichen Treffen Empfehlungen aus.<\/p><\/blockquote>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich eine gelungene Veranstaltung aus?<\/strong><\/p>\n<p>Zufriedene G\u00e4ste<\/p>\n<p><strong>Was ist das Schlimmste, das dir ein Gast antun kann? Z. B. f\u00fcnfmal hintereinander \u201eAtemlos\u201c w\u00fcnschen, ins Mischpult greifen, \u2026?<\/strong><\/p>\n<p>Das einzige, was ich nicht mag, ist, wenn jemand ungefragt an meine Technik geht.<\/p>\n<p><strong>Ist schon mal bei einer deiner Veranstaltungen so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Einmal habe ich meine Festplatte mit den vorbereiten Liedern vergessen, aber das passiert mir nie wieder. Inzwischen habe ich all meine Lieder auf meinem Laptop und 2 Backup-Festplatten dabei und ein Online-Backup. Klingt jetzt etwas paranoid, aber das war mir sooo peinlich, das soll mir nie wieder passieren.<\/p>\n<h3>Erfahrung als Dienstleister<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als Dienstleister?<\/strong><\/p>\n<blockquote><p>Der DJ, der mega geil Party gemacht hat<\/p><\/blockquote>\n<p>Als ich auf der Stra\u00dfe von mir nicht bekannten Personen angesprochen wurde, die meinten: &#8220;Hey, du bist doch der DJ, der damals so mega geil Party gemacht hat.&#8221;<\/p>\n<p><strong>Wie lernt man deinen Job deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man diesen Job machen m\u00f6chte?<\/strong><\/p>\n<p>Voraussetzung ist die Liebe zur Musik und dann hei\u00dft es, sich mit vielen Themen wie Harmonie oder Taktgef\u00fchl auseinanderzusetzen. Und dann gilt der Grundsatz: \u00fcben, \u00fcben, \u00fcben und nochmals \u00fcben.<\/p>\n<p><strong>Was bedeutet\u00a0<a title=\"evely.com\" href=\"https:\/\/www.evely.com\/?utm_source=blog&amp;utm_medium=referral&amp;utm_campaign=link&amp;utm_content=\/blog\/\">evely.com<\/a>\u00a0f\u00fcr dich?<\/strong><\/p>\n<p>EVELY ist eine Top Homepage, auf der man sofort sieht, was man f\u00fcr sein Geld bekommt. Ich habe einen enormen Zuwachs an Anfragen bekommen, seit ich bei evely.com bin.<\/p>\n<h2>Habt ihr Fragen an Manuel?<\/h2>\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview. <a href=\"https:\/\/www.evely.com\/djs\/dj-mika-aida-dj-3206.html\">Hier findet ihr weitere Infos zu Manuel und k\u00f6nnt ihn direkt f\u00fcr eure Veranstaltung buchen.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manuel bringt als DJ aus Baden-W\u00fcrttemberg \u00fcber 10 Jahre Erfahrung in dem Job mit und tritt unter anderem in Augsburg, N\u00fcrnberg und Mainz auf. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, schaut euch unser DJ-Interview mit ihm an. Nat\u00fcrlich k\u00f6nnt ihr Manuel auch direkt hier buchen. Manuel \u00fcber sich selbst &amp; Musik [&hellip;]<\/p>\n","protected":false},"author":720,"featured_media":8227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[848],"post_status":[],"class_list":["post-8219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","tag-dj-interview","quellenhinweis-manuel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Manuel (DJ Mika Aida) - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"In seinem DJ Interview erz\u00e4hlt uns Manuel aus Baden-W\u00fcrttemberg, was f\u00fcr ihn die Faszination f\u00fcr Musik ausmacht und wie er zum DJing kam.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Manuel (DJ Mika Aida) - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"In seinem DJ Interview erz\u00e4hlt uns Manuel aus Baden-W\u00fcrttemberg, was f\u00fcr ihn die Faszination f\u00fcr Musik ausmacht und wie er zum DJing kam.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T11:18:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T11:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bela\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Manuel (DJ Mika Aida) - EVELY-Blog","description":"In seinem DJ Interview erz\u00e4hlt uns Manuel aus Baden-W\u00fcrttemberg, was f\u00fcr ihn die Faszination f\u00fcr Musik ausmacht und wie er zum DJing kam.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Manuel (DJ Mika Aida) - EVELY-Blog","og_description":"In seinem DJ Interview erz\u00e4hlt uns Manuel aus Baden-W\u00fcrttemberg, was f\u00fcr ihn die Faszination f\u00fcr Musik ausmacht und wie er zum DJing kam.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2019-01-17T11:18:31+00:00","article_modified_time":"2019-05-15T11:15:02+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png","type":"image\/png"}],"author":"Bela","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206"},"author":{"name":"Bela","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/81fecac5349b1287415a8c09a14f3b1f"},"headline":"DJ-Interview mit Manuel","datePublished":"2019-01-17T11:18:31+00:00","dateModified":"2019-05-15T11:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206"},"wordCount":794,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png","keywords":["DJ-Interview"],"articleSection":["DJ-Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206","name":"DJ Interview mit Manuel (DJ Mika Aida) - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png","datePublished":"2019-01-17T11:18:31+00:00","dateModified":"2019-05-15T11:15:02+00:00","description":"In seinem DJ Interview erz\u00e4hlt uns Manuel aus Baden-W\u00fcrttemberg, was f\u00fcr ihn die Faszination f\u00fcr Musik ausmacht und wie er zum DJing kam.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_mika_aida_dj-3206-EVELY.jpg.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-mika-aida-dj-3206#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Manuel"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/81fecac5349b1287415a8c09a14f3b1f","name":"Bela","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","caption":"Bela"},"description":"Bela ist immer auf der Suche nach neuer Musik. Egal f\u00fcr welchen Anlass, Musik darf bei ihm nie fehlen und sein Herz schl\u00e4gt besonders f\u00fcr Hip-Hop. Au\u00dferdem begeistert sich Bela f\u00fcr verschiedenste Sportarten von American Football bis hin zum Schwimmen.","url":"https:\/\/www.evely.com\/blog\/author\/bela"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/720"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=8219"}],"version-history":[{"count":8,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8219\/revisions"}],"predecessor-version":[{"id":9452,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8219\/revisions\/9452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/8227"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=8219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=8219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=8219"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=8219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}