{"id":8397,"date":"2019-02-17T16:26:15","date_gmt":"2019-02-17T15:26:15","guid":{"rendered":"https:\/\/www.evely.com\/blog\/?p=8397"},"modified":"2019-01-28T17:55:56","modified_gmt":"2019-01-28T16:55:56","slug":"dj-franz-3748","status":"publish","type":"post","link":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748","title":{"rendered":"DJ-Interview mit Franz"},"content":{"rendered":"<p>Franz kommt aus <a href=\"https:\/\/www.evely.com\/dj-bayern.html\">Bayern<\/a> und tritt als DJ regelm\u00e4\u00dfig vor 1.500 Leuten auf. Er hat schon 4 Jahre Erfahrung als Discjockey und arbeitet daran, sich stetig weiterzuentwickeln. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. <a href=\"https:\/\/www.evely.com\/djs\/dj-franz-3748.html\">Nat\u00fcrlich k\u00f6nnt ihr Franz auch direkt hier buchen.<\/a><\/p>\n<h2>Franz \u00fcber sich selbst &amp; Musik<\/h2>\n<h3>Zur Person<\/h3>\n<p><strong>Wie bist du zu deinem Job gekommen und was fasziniert dich daran?<\/strong><\/p>\n<p>W\u00e4hrend der 80er und 90er Jahre zog ich mit unserer 5- bis 7-Mann-Band durch die Tanzs\u00e4le Niederbayerns. Jugendb\u00e4lle, Hochzeiten und Firmenfeiern wurden musikalisch versorgt. Musikrichtung von Abba bis ZZ-Top. Ich spielte Gitarre und sang auch.<\/p>\n<blockquote><p>Ich liebe und lebe Musik.<\/p><\/blockquote>\n<p>2015 stolperte ich per Zufall \u00fcber eine Musiksoftware, bald kam der erste Controller. Zuerst im Freundeskreis, dann bei Vereinen und schlie\u00dflich folgten erste Hochzeiten und Club-Gigs. Ich liebe und lebe Musik. \ud83d\ude09<\/p>\n<p><strong>Was macht dich als Dienstleister unschlagbar? Warum sollte man dich buchen?<\/strong><\/p>\n<p>Ich bin Dienstleister und Servicemensch. Der Auftraggeber soll wenig mit der Technik und der Organisation der Musik und Beleuchtung besch\u00e4ftigt sein m\u00fcssen.<\/p>\n<p><strong>F\u00fcr welche Events eignest du dich besonders gut?<\/strong><\/p>\n<p>Meine Favoriten sind Hochzeiten, Feiern allgemein, Tanzevents und gerne auch ausgefallene Eventthemen.<\/p>\n<h3>Angebot, Technik und Service<\/h3>\n<p><strong>Wie beschreibst du dein Angebot? Z. B. welche Musik oder Lieder spielst du gerne?<\/strong><\/p>\n<blockquote><p>Mein Genre deckt alles ab.<\/p><\/blockquote>\n<p>&#8220;Das Sch\u00f6nste, was F\u00fc\u00dfe tun k\u00f6nnen, ist tanzen!&#8221; Dieser Spruch hat sich bei mir sehr eingepr\u00e4gt und begleitet mich mein halbes Leben. \ud83d\ude42 Mein Genre deckt alles ab, von den 60ern bis aktuell, gerne Funk, Soul, Rock, Disco aber auch mal Dark.<\/p>\n<p><strong>Beschreibe deine Ausr\u00fcstung: Was k\u00f6nnen Kunden erwarten, wenn sie dich buchen? Welche Technik, Instrumente etc. bringst du mit?<\/strong><\/p>\n<p>Die Austattung ist flexibel, f\u00fcr Events von 10 bis 100 Personen, top Subwoofer und Boxen, Lichtanlage und Nebelmaschine bei Bedarf.<\/p>\n<p><strong>Welche besonderen F\u00e4higkeiten oder Leistungen bringst du als Dienstleister mit?<\/strong><br \/>\nDie Erfahrung in der Band kommt mir bei <a href=\"https:\/\/www.evely.com\/blog\/anbieter\/dj\/allgemein\/dj-moderator-tipps\">Moderation<\/a> und Animation zu Gute, ich kann aber auch in den Hintergrund treten und von dort aus durch die Musikauswahl f\u00fcr Stimmung sorgen.<\/p>\n<blockquote><p>Durch die Musikauswahl f\u00fcr Stimmung sorgen<\/p><\/blockquote>\n<h3>Vor der Veranstaltung<\/h3>\n<p><strong>Worauf sollten Kunden besonders achten, wenn sie nach einem Dienstleister wie dir f\u00fcr ihre Veranstaltung suchen?<\/strong><\/p>\n<p>Zuverl\u00e4ssige Abwicklung der Buchung mit umfassender Beratung vor dem Event und Betreuung w\u00e4hrend des Events.<\/p>\n<p><strong>Wie bereitest du einen Auftritt vor und wie beziehst du deine Kunden dabei ein?<\/strong><\/p>\n<p>Beim Vorgespr\u00e4ch gehe ich die Liste der Genres bzw. Musikrichtungen durch, kl\u00e4re das Ausma\u00df der Moderationst\u00e4tigkeit usw. und checke die Technik vor Ort bzw. den Technik-Bedarf vorher ab.<\/p>\n<h3>W\u00e4hrend der Veranstaltung<\/h3>\n<p><strong>Was macht f\u00fcr dich eine gelungene Veranstaltung aus?<\/strong><\/p>\n<p>Tanzende, feiernde, lachende und gl\u00fcckliche Menschen<\/p>\n<p><strong>Was ist das Schlimmste, das dir ein Gast antun kann? Z. B. f\u00fcnfmal hintereinander \u201eAtemlos\u201c w\u00fcnschen, ins Mischpult greifen, \u2026?<\/strong><\/p>\n<blockquote><p>Freundlich aber bestimmt<\/p><\/blockquote>\n<p>W\u00fcnsche sind wichtig und geben Inspiration und Feedback, aber im richtigen Ma\u00df &#8230; Ins Mischpult zu greifen oder die Technik zu manipulieren ist ein No Go, was ich freundlich aber bestimmt zur\u00fcckweisend l\u00f6se.<\/p>\n<p><strong>Ist schon mal bei einer deiner Veranstaltungen so richtig was schiefgegangen? Wie hast du reagiert bzw. wie bist du auf so etwas vorbereitet?<\/strong><\/p>\n<p>Ja, der Strom f\u00e4llt aus, die Technik h\u00e4ngt, den falschen Knopf gedr\u00fcckt &#8230; alles schon passiert. Ich fange dann an, zu singen und Sp\u00e4\u00dfe zu machen und die Zeit zu \u00fcberbr\u00fccken.<\/p>\n<h3>Erfahrung als Dienstleister<\/h3>\n<p><strong>Was war dein \u00fcberraschendstes Erlebnis als Dienstleister?<\/strong><\/p>\n<p>Wenn du selber G\u00e4nsehaut bekommst, weil die Musik gut ankommt.<\/p>\n<p><strong>Wie lernt man deinen Job deiner Meinung nach am besten? Was sollte man mitbringen und worauf sollte man achten, wenn man diesen Job machen m\u00f6chte?<\/strong><\/p>\n<blockquote><p>Talent, Einf\u00fchlungsverm\u00f6gen, Flexibilit\u00e4t und Offenheit<\/p><\/blockquote>\n<p>Naja, etwas Talent und Einf\u00fchlungsverm\u00f6gen geh\u00f6ren dazu, auch Flexibilit\u00e4t und Offenheit, was Musikgeschmack anbetrifft. Und \u00dcbung macht bekanntlich den Meister.<\/p>\n<p><strong>Was bedeutet\u00a0<a title=\"evely.com\" href=\"https:\/\/www.evely.com\/?utm_source=blog&amp;utm_medium=referral&amp;utm_campaign=link&amp;utm_content=\/blog\/\">evely.com<\/a>\u00a0f\u00fcr dich?<\/strong><\/p>\n<p>Eine Top-Adresse f\u00fcr die Vermittlung von DJs und K\u00fcnstlern, eine super Plattform f\u00fcr Promotion<\/p>\n<h2>Habt ihr Fragen an Franz?<\/h2>\n<p>Dann hinterlasst einfach einen Kommentar unter diesem Interview. <a href=\"https:\/\/www.evely.com\/djs\/dj-franz-3748.html\">Hier findet ihr weitere Infos zu Franz und k\u00f6nnt ihn direkt f\u00fcr eure Veranstaltung buchen.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franz kommt aus Bayern und tritt als DJ regelm\u00e4\u00dfig vor 1.500 Leuten auf. Er hat schon 4 Jahre Erfahrung als Discjockey und arbeitet daran, sich stetig weiterzuentwickeln. Damit ihr euch ein genaueres Bild von ihm machen k\u00f6nnt, hat er uns im Folgenden einige Interview-Fragen beantwortet. Nat\u00fcrlich k\u00f6nnt ihr Franz auch direkt hier buchen. Franz \u00fcber [&hellip;]<\/p>\n","protected":false},"author":720,"featured_media":8398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[848],"post_status":[],"class_list":["post-8397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-djs","tag-dj-interview","quellenhinweis-franz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DJ Interview mit Franz - EVELY-Blog<\/title>\n<meta name=\"description\" content=\"Franz legt auf Veranstaltungen aller Art auf und bringt ein breit gef\u00e4chertes Repertoire an Musik aus diversen Jahrzehnten mit. Lest hier sein DJ-Interview.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DJ Interview mit Franz - EVELY-Blog\" \/>\n<meta property=\"og:description\" content=\"Franz legt auf Veranstaltungen aller Art auf und bringt ein breit gef\u00e4chertes Repertoire an Musik aus diversen Jahrzehnten mit. Lest hier sein DJ-Interview.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EVELYcom\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-17T15:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bela\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DJ Interview mit Franz - EVELY-Blog","description":"Franz legt auf Veranstaltungen aller Art auf und bringt ein breit gef\u00e4chertes Repertoire an Musik aus diversen Jahrzehnten mit. Lest hier sein DJ-Interview.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748","og_locale":"de_DE","og_type":"article","og_title":"DJ Interview mit Franz - EVELY-Blog","og_description":"Franz legt auf Veranstaltungen aller Art auf und bringt ein breit gef\u00e4chertes Repertoire an Musik aus diversen Jahrzehnten mit. Lest hier sein DJ-Interview.","og_url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748","og_site_name":"Blog von EVELY.com","article_publisher":"https:\/\/www.facebook.com\/EVELYcom","article_published_time":"2019-02-17T15:26:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png","type":"image\/png"}],"author":"Bela","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#article","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748"},"author":{"name":"Bela","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/81fecac5349b1287415a8c09a14f3b1f"},"headline":"DJ-Interview mit Franz","datePublished":"2019-02-17T15:26:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748"},"wordCount":719,"commentCount":0,"publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png","keywords":["DJ-Interview"],"articleSection":["DJ-Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748","url":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748","name":"DJ Interview mit Franz - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#primaryimage"},"image":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#primaryimage"},"thumbnailUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png","datePublished":"2019-02-17T15:26:15+00:00","description":"Franz legt auf Veranstaltungen aller Art auf und bringt ein breit gef\u00e4chertes Repertoire an Musik aus diversen Jahrzehnten mit. Lest hier sein DJ-Interview.","breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#primaryimage","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2019\/01\/dj_franz-3748-EVELY.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/kunden\/interviews\/djs\/dj-franz-3748#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DJ-Interview mit Franz"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]},{"@type":"Person","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/person\/81fecac5349b1287415a8c09a14f3b1f","name":"Bela","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc0ea36ced72efca1d58930bc90486631ede299503085c2bed64471a99bf1629?s=96&d=mm&r=g","caption":"Bela"},"description":"Bela ist immer auf der Suche nach neuer Musik. Egal f\u00fcr welchen Anlass, Musik darf bei ihm nie fehlen und sein Herz schl\u00e4gt besonders f\u00fcr Hip-Hop. Au\u00dferdem begeistert sich Bela f\u00fcr verschiedenste Sportarten von American Football bis hin zum Schwimmen.","url":"https:\/\/www.evely.com\/blog\/author\/bela"}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/users\/720"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/comments?post=8397"}],"version-history":[{"count":3,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8397\/revisions"}],"predecessor-version":[{"id":8421,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts\/8397\/revisions\/8421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media\/8398"}],"wp:attachment":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/media?parent=8397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/categories?post=8397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags?post=8397"},{"taxonomy":"post_status","embeddable":true,"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/post_status?post=8397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}