{"id":517,"count":2,"description":"","link":"https:\/\/www.evely.com\/blog\/tag\/firmenparty","name":"Firmenparty","slug":"firmenparty","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Firmenparty - EVELY-Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firmenparty - EVELY-Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evely.com\/blog\/tag\/firmenparty\" \/>\n<meta property=\"og:site_name\" content=\"Blog von EVELY.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firmenparty - EVELY-Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Firmenparty - EVELY-Blog","og_url":"https:\/\/www.evely.com\/blog\/tag\/firmenparty","og_site_name":"Blog von EVELY.com","og_image":[{"width":700,"height":350,"url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.evely.com\/blog\/tag\/firmenparty","url":"https:\/\/www.evely.com\/blog\/tag\/firmenparty","name":"Firmenparty - EVELY-Blog","isPartOf":{"@id":"https:\/\/www.evely.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.evely.com\/blog\/tag\/firmenparty#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evely.com\/blog\/tag\/firmenparty#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.evely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Firmenparty"}]},{"@type":"WebSite","@id":"https:\/\/www.evely.com\/blog\/#website","url":"https:\/\/www.evely.com\/blog\/","name":"EVELY-Blog","description":"Einfach feiern!","publisher":{"@id":"https:\/\/www.evely.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evely.com\/blog\/#organization","name":"EVELY","alternateName":"EVELY.com","url":"https:\/\/www.evely.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","contentUrl":"https:\/\/www.evely.com\/blog\/wp-content\/uploads\/2025\/09\/logo_compact.png","width":700,"height":350,"caption":"EVELY"},"image":{"@id":"https:\/\/www.evely.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EVELYcom","https:\/\/www.instagram.com\/EVELYcom","https:\/\/www.pinterest.de\/EVELYcom"]}]}},"_links":{"self":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.evely.com\/blog\/wp-json\/wp\/v2\/posts?tags=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}